{"id":85,"date":"2011-03-28T17:44:00","date_gmt":"2011-03-28T17:44:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/?p=85"},"modified":"2011-03-28T17:44:00","modified_gmt":"2011-03-28T17:44:00","slug":"vinos-al-sur-la-mancha-vinos-luz","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/2011\/03\/28\/vinos-al-sur-la-mancha-vinos-luz\/","title":{"rendered":"VINOS AL SUR DE LA MANCHA: VINOS DE LUZ"},"content":{"rendered":"\n<p class=\"MsoNormal\" style=\"text-align: justify;\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Habr\u00e1 que decirlo para quienes no lo sepan: los lugares, el paisaje y el ambiente biodiverso del sur de la provincia de Ciudad Real son de una belleza tan serena e intensa que te sustraen la raz\u00f3n si por all\u00ed deambulas; <span style=\"\"> <\/span>y bien puedes acabar como don Quijote, que por esos lares anduvo entre enso\u00f1aciones y dislates.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">All\u00e1 donde La Mancha rinde su infinitud a los pies de la Sierra de Alcaraz, de Sierra Morena, y hasta el desfiladero de Despe\u00f1aperros, a trav\u00e9s de las estaciones nos encontramos con la madre naturaleza que desata sus pasiones por causa del v\u00e9rtigo de la altitud, siempre por encima de los ochocientos metros.<span style=\"\">  <\/span>Bien sea en pleno invierno, cuando las inmensas dehesas, moteadas de encinas, ocultan en un velo neblinoso de misterio la profundidad de sus tierras oscuras; o en la primavera cuando, ante un inacabable manto de verdor, empieza a desperezarse un sol que, presto en el verano, quemar\u00e1 sin piedad todo ser vivo que se mueva o no.<span style=\"\">  <\/span>Toda la vida natural que por all\u00ed se da, desde el lagarto ocelado al b\u00faho real, pasando por una locura de perdices y de conejos que se meten entre las ruedas de los coches, desorientados e ignorantes del fin que les espera cuando ej\u00e9rcitos de cazadores urbanos lleguen en el oto\u00f1o; toda esa vida en realidad sirve de acompa\u00f1amiento a los casi \u00faltimos invitados al terreno: los vi\u00f1edos que, desde tiempo inmemorial y de un modo inveros\u00edmil, se ense\u00f1orean de los campos labrados y marcan un horizonte, tambi\u00e9n vestido por el<span style=\"\">  <\/span>olivar.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Las razones por las que se plant\u00f3 tanto vi\u00f1edo en La Mancha son obvias y ahora ya no son pertinentes pues la historia es totalmente otra. Pero fij\u00e9monos en las tierras altas que van desde los altos del Bonillo \u2013a la vera de las Lagunas de Ruidera- recorriendo todo el Campo de Montiel hasta cerca de Valdepe\u00f1as, en el embalse de La Cabezuela, que hace del r\u00edo Jabal\u00f3n un peque\u00f1o mar interior con una avifauna pujante, ahora todo bendecido con dos a\u00f1os consecutivos de intensas lluvias. Esos parajes amaestrados, pero inh\u00f3spitos y solitarios, han venido a hospedar -\u00a1qu\u00e9 cosas!- a modernas bodegas que est\u00e1n elaborando vinos que claramente proyectan la zona<span style=\"\">  <\/span>donde nacen.<span style=\"\">  <\/span>Tanto en suelos pedregosos, o de arcillas expansivas, o muy pobres, <span style=\"\"> <\/span>junto a otros m\u00e1s fecundos, en cualquier caso los protagonistas son la vida natural en estado puro en medio de un clima cruel, y el sol omnipotente durante todo el ciclo vegetativo de la vid.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"\" lang=\"ES-TRAD\">Este paisaje y ambiente geoclim\u00e1tico de clima continental extremado (clima \u00fanico, monocorde, a diferencia de los que se dan en la Ribera del Duero <span style=\"\"> <\/span>y en La Rioja) escasa pluviometr\u00eda y que por ello disfruta de cielos altos y despejados casi todos los d\u00edas del a\u00f1o da la siguiente ecuaci\u00f3n: altitud, m\u00e1s aires limpios y cielos abiertos, es igual a luz.<span style=\"\">  <\/span>Una luz inmaculada, tan pr\u00edstina e inaprehensible que te hace saltar las l\u00e1grimas no se sabe si por la imposibilidad del ojo de captar esos matices puros que propicia la radiaci\u00f3n solar,<span style=\"\">  <\/span>o de emoci\u00f3n al sentir que est\u00e1s respirando lo mismo que respiraban nuestros ancestros: un ambiente natural, intocado, en medio de un embeleso de solitud y silencio de vida salvaje que comparte h\u00e1bitat con los humanos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><IMG src=\"\/\/static-blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-content\/uploads\/sites\/19\/villamanrique2010121.jpg\" id=\"img_2\" class=\"imgcen\"><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"\">    <\/span>DOS BODEGAS DE VILLAMANRIQUE Y OTRA M\u00c1S<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Villamanrique es ese otro lugar de La Mancha de cuyo nombre a ver qui\u00e9n se acuerda si no soy yo, que aqu\u00ed nac\u00ed y<span style=\"\">  <\/span>aqu\u00ed me he venido desterrado por causa de mi estulticia supina al dejarme enga\u00f1ar por una mujer,<span style=\"\">  <\/span>falsa en toda hora y traidora al fin,<span style=\"\">  <\/span>hasta destrozar mi vida que ahora intento recomponer en estas tierras rojas de verg\u00fcenza y pardas de dolor.<span style=\"\">  <\/span>Y, \u00a1oh sorpresa! en estos lugares alejados de todas partes pero sin duda en un ambiente de encanto especial se encuentran tres bodegas que son las \u00faltimas en latitud de esta tierra \u00faltima de frontera.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Bodegas Real, situada a orillas del embalse de La Cabezuela en la carretera de Valdepe\u00f1as a C\u00f3zar, es un muy buen ejemplo del esfuerzo por tratar de cambiar la imagen -\u00bfqu\u00e9 imagen?-<span style=\"\">  <\/span>que de La Mancha suele tener una parte del gran p\u00fablico amante<span style=\"\">  <\/span>de los vinos; por eso salen las botellas con contraetiqueta de Vinos de la Tierra de Castilla, como tantos otros vinos rompedores de bodegas manchegas.<span style=\"\">  <\/span>Fundada por Sergio Barroso en el a\u00f1o 1984, quien compr\u00f3 la Finca Maris\u00e1nchez con el objetivo \u2013desde una perspectiva visionaria- de apostar por una bodega con vi\u00f1edo multivarietal y en espaldera, que fue previo al boom del vino espa\u00f1ol. En 1989 se construy\u00f3 la bodega para producir vinos de calidad, de alguna manera algo extra\u00f1o en La Mancha de entonces.<span style=\"\">  <\/span>En 2002 de nuevo se adelantan al futuro y empiezan con el enoturismo, adaptando el cortijo del siglo XVIII; finalmente dotaron de restaurante y salones al complejo. La tempranillo es la base de los vinos, y ahora que las cepas llegan a la mayor\u00eda de edad, sobre todo el Finca Maris\u00e1nchez es un vino a seguir pues aquilata ese potencial del terru\u00f1o y la variedad.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Finca Maris\u00e1nchez 2006. En el reconvertido mapa vitivin\u00edcola de la vieja pen\u00ednsula ib\u00e9rica las cosas est\u00e1n cambiando; surgen por doquier vinos que otrora eran s\u00f3lo quimeras quijotescas.<span style=\"\">   <\/span>Este vino de Bodegas Real es<span style=\"\">  <\/span>un magn\u00edfico ejemplo de vino emergente.<span style=\"\">  <\/span>Terrenos altos, clima continental extremado, respeto por la biodiversidad en un ambiente<span style=\"\">  <\/span>bell\u00edsimo de paz<span style=\"\">  <\/span>y serenidad absolutamente sano y natural.<span style=\"\">  <\/span>Picota intenso.<span style=\"\">  <\/span>Impecable en nariz con aromas sugerentes de frutas y terru\u00f1o arropados por un roble ex\u00f3tico que evoca<span style=\"\">  <\/span>perfumes que casi se mastican<span style=\"\">  <\/span>(flores, especias. cacao).<span style=\"\">  <\/span>Sorprendentemente fresco y vivo en el paso de boca;<span style=\"\">  <\/span>amable y con taninos vigorosos, y con finura.<span style=\"\">  <\/span>Un encanto<span style=\"\">  <\/span>sensorial<span style=\"\">  <\/span>de una tierra encantada. Y con proyecci\u00f3n internacional.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Bodega Abaxterra es el voluntarioso esfuerzo y sue\u00f1o hecho realidad de Enrique Bilbao que, aunque viene del mundo de la educaci\u00f3n, es bi\u00f3logo;<span style=\"\">  <\/span>y esa formaci\u00f3n le est\u00e1 sirviendo de mucha ayuda tano en la vi\u00f1a como en los procesos de vinificaci\u00f3n.<span style=\"\">  <\/span>Justo a la vera de la carretera que va de Torre de Juan Abad a Castellar de Santiago, y donde lo rural es verdaderamente una certeza, se encuentra una peque\u00f1a finca con un vi\u00f1edo (sobre todo tempranillo y syrah) mimado; y ah\u00ed se alza un edificio mimetizado en el entorno, sin adornos innecesarios y contando con el espacio como \u00fanico lujo.<span style=\"\">  <\/span>Dep\u00f3sitos de \u00faltima tecnolog\u00eda, <span style=\"\"> <\/span>una coqueta sala de barricas y el empe\u00f1o de hacer las cosas bien.<span style=\"\">  <\/span>La impronta de la bodega marca un car\u00e1cter innovador, exclusivo y fuertemente comprometido con la calidad.<span style=\"\">  <\/span>Y ello parece que va ser cierto si nos atenemos a los resultados: su primer vino ABAXTERRA tinto roble 2009, es un logro en todos los sentidos.<span style=\"\">  <\/span>Presentaci\u00f3n excelente para un vino que tiene y promete. Bonito vestido de rojo cereza intenso; aromas limpios de frutos maduros que evocan un paisaje seductor de monte y flores, con leves toques l\u00e1cteos y atisbos de roble que completan el trago, que es de cuerpo medio y sustancioso; si se le da la oportunidad al vino, este acaba mostrando un empaque de vino serio y de muy buenas prestaciones sensoriales. Sin duda un vino a seguir.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><IMG src=\"\/\/static-blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-content\/uploads\/sites\/19\/246860_villamanrique2010229.jpg\" id=\"img_0\" class=\"imgcen\"><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Al lado de la anterior se encuentra otra finca, \u201cGuadianeja\u201d, m\u00e1s extensa -850 hect\u00e1reas- y con un vi\u00f1edo m\u00e1s asentado, de treinta y cuarenta a\u00f1os (probablemente sea de los primeros cabernets que se plantaron en La Mancha) <span style=\"\"> <\/span>y cuyas uvas tambi\u00e9n de garnacha y tempranillo abastecieron a una gran bodega de Manzanares.<span style=\"\">  <\/span>Hoy en d\u00eda -desde 2002- con una nueva propiedad y marca, Bodega y Vi\u00f1edos Tikalo,<span style=\"\">  <\/span>contin\u00faan vendimiando a mano el rendimiento muy escaso de las cepas y vinificando con un enfoque hacia la obtenci\u00f3n del mejor vino de uvas de calidad que condensan lo mejor del suelo y del clima que las marca.<span style=\"\">  <\/span>Tambi\u00e9n se da en la finca el olivar, con una producci\u00f3n de aceite<span style=\"\">  <\/span>de gran calidad. La bodega \u2013como las de los alrededores- precisa de proyecci\u00f3n y de un mejor posicionamiento comercial.<span style=\"\">  <\/span>Su vino Kios 2004, es una buena muestra de lo que decimos: sin excesos de roble pero con una gran expresi\u00f3n frutal, el vino presenta aromas (en la muestra catada ya en fase de declive) de frutos negros, mermeladas y alg\u00fan toque que recuerda al chocolate con leche; acidez compensada y de cuerpo medio,<span style=\"\">  <\/span>el vino acusa el paso del tiempo pero seguro que otras a\u00f1adas m\u00e1s recientes han de ser m\u00e1s expresivas.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Es frustrante que la gente de la comarca desconozca, no sepa apreciar, la riqueza y el lujo de esos vinos de calidad a precios ajustados.<span style=\"\">  <\/span>Y a los consumidores de otros lugares no les llega el mensaje de los vinos de sol y luz de esta tierra encantada.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Habr\u00e1 que decirlo para quienes no lo sepan: los lugares, el paisaje y el ambiente biodiverso del sur de la provincia de Ciudad Real son de una belleza tan serena e intensa que te sustraen la raz\u00f3n si por all\u00ed deambulas; y bien puedes acabar como don Quijote, que por esos lares anduvo entre enso\u00f1aciones [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-85","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}