{"id":89,"date":"2011-05-22T12:03:00","date_gmt":"2011-05-22T12:03:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/?p=89"},"modified":"2011-05-22T12:03:00","modified_gmt":"2011-05-22T12:03:00","slug":"indignacion-emocion","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/2011\/05\/22\/indignacion-emocion\/","title":{"rendered":"INDIGNACI\u00d3N\/EMOCI\u00d3N"},"content":{"rendered":"\n<p class=\"MsoNormal\" style=\"text-align: justify;\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\">La ola de indignaci\u00f3n\/emoci\u00f3n que est\u00e1 recorriendo el pa\u00eds por el movimiento espont\u00e1neo del 15-M, aparte de refrescante, regeneradora e ilusionante, es la constataci\u00f3n del refr\u00e1n castellano que dice que no hay mal que cien a\u00f1os dure ni cuerpo que lo aguante.<span style=\"\">  <\/span>Y en esta Espa\u00f1a nuestra, <span style=\"\"> <\/span>treinta y cuatro a\u00f1os de &#8220;falsa&#8221; democracia ha dado para esto, para una partitocracia espeluznante, escler\u00f3tica, demente e insultante. Recuerdo en los a\u00f1os ochenta del pasado siglo -cuando estaba yo en el Reino Unido- escuchar a la Premier Margaret Thatcher hablar con tono despectivo de la democracia espa\u00f1ola; que la nuestra no se pod\u00eda comparar. Aquello me fastidi\u00f3, pero las verdad es que el sistema all\u00ed s\u00ed que es realmente representativo, sin listas cerradas y sin tanto mareamiento de la perdiz ante cualquier tema; m\u00e1s bien realismo y pragmatismo.<span style=\"\">  <\/span>Pero bueno, lo cierto es que lo que hemos conseguido aqu\u00ed <span style=\"\"> <\/span>(que ha sido much\u00edsimo) ha sido el resultado del trabajo y sentido com\u00fan de las bases, del com\u00fan de la poblaci\u00f3n.<span style=\"\">  <\/span>Y creo que con los mismos postulados que ahora estamos viendo en las plazas espa\u00f1olas.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">VINO INDIGNADO<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Mas no quiero ahora<span style=\"\">  <\/span>modificar el sentido de este blog.<span style=\"\"> La vida est\u00e1 para ser vivida con dignidad. El vino est\u00e1 para ser <\/span><span style=\"\">bebido con placer. <\/span>Aqu\u00ed a lo que estamos es a lo que preocupa a un sumiller desde el punto de vista de la vocaci\u00f3n de servicio.<span style=\"\">  <\/span>Las personas que comen y beben y demandan productos y servicios de calidad y a precios razonables.<span style=\"\">  <\/span>El vino.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">He de decir que de alguna manera los mismos lastres que arrastra la clase pol\u00edtica espa\u00f1ola los sufre el mundo del vino: dinero para proveerse y crear grandes productos y servicios, pero luego una gesti\u00f3n de esos productos y servicios que ignora su sentido \u00faltimo: que los destinatarios son las personas de a pie. Para m\u00ed como prescriptor me resulta doloroso que tant\u00edsimo vino de una calidad maravillosa como lo que se elabora en Espa\u00f1a, est\u00e9 en cantidades ingentes en las bodegas sin vender. \u00bfPor qu\u00e9?<span style=\"\">  <\/span>Pues porque los departamentos comerciales y promocionales los conducen, los trabajan personas que adolecen de un mal parecido <span style=\"\"> <\/span>al de los pol\u00edticos:<span style=\"\">  <\/span>el sueldo fijo, la poltrona, la falta de sensibilidad con la gente de la calle y sus verdaderas inquietudes.<span style=\"\">  <\/span>Se funciona de espaldas a la gente.<span style=\"\">  <\/span>Y esto pasa desgraciadamente en casi todas las facetas de la vida.<span style=\"\">  <\/span>Cuando se atiende a un cliente se est\u00e1 mirando al ordenador en vez de a sus ojos; cuando se produce o se lanza un producto lo hacen con t\u00e9cnicas de m\u00e1rquetin cuyos resultados buscan agradar al que contrata, no a quienes va dirigido.<span style=\"\">    <\/span>Y as\u00ed pod\u00edamos continuar\u2026<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Quiera la buena voluntad de la gente que generaciones m\u00e1s concienciadas logren una suerte de equilibrio para llevar a buen puerto sus expectativas vitales, el mismo equlibrio que es imprescindible cuando hablamos de un buen vino.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La ola de indignaci\u00f3n\/emoci\u00f3n que est\u00e1 recorriendo el pa\u00eds por el movimiento espont\u00e1neo del 15-M, aparte de refrescante, regeneradora e ilusionante, es la constataci\u00f3n del refr\u00e1n castellano que dice que no hay mal que cien a\u00f1os dure ni cuerpo que lo aguante. Y en esta Espa\u00f1a nuestra, treinta y cuatro a\u00f1os de &#8220;falsa&#8221; democracia ha [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}