{"id":93,"date":"2011-07-14T09:48:00","date_gmt":"2011-07-14T09:48:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/?p=93"},"modified":"2011-07-14T09:48:00","modified_gmt":"2011-07-14T09:48:00","slug":"lugares-donde-esta-vino","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/2011\/07\/14\/lugares-donde-esta-vino\/","title":{"rendered":"LUGARES DONDE NO EST\u00c1 EL VINO"},"content":{"rendered":"<p><P style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\" class=MsoNormal><FONT size=3 face=Calibri>Tanto hablar de vinos y de su presencia aqu\u00ed y all\u00e1; y nunca se me hab\u00eda ocurrido considerar donde no se encuentra el vino y por qu\u00e9. (Esta consideraci\u00f3n viene a prop\u00f3sito del tema tan manido en boca de bodegueros y dem\u00e1s sectores implicados en la producci\u00f3n del vino: que se compra o se consume poco.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Poco para lo que se produce; imagino).<\/FONT><\/p>\n<p> <P style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\" class=MsoNormal><FONT size=3 face=Calibri>El vino no te lo encontrar\u00e1s en la casa de los pusil\u00e1nimes que no saben gozar del impulso de vivir.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Tampoco lo ver\u00e1s en los museos donde se guardan reliquias de otros tiempos u objetos muertos.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Ni en los templos de las religiones ni en las casas de los parlamentos ni en los palacios de justicia donde se maquinan formas de sometimiento y de castigo para las personas.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Tampoco es probable verlo en los lupanares, que son la negaci\u00f3n de la sensibilidad y donde se comercia de un modo berrendo con las emociones que pretenden suscitar el uso bastardo de los sentidos.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>(Eso lo supongo, pues la verdad es que a estas alturas de la vida nunca entr\u00e9 ah\u00ed).<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>En los salones de baile no creo que haya vino toda vez que cuando baila el cuerpo no baila la mente o la imaginaci\u00f3n.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Sorprendentemente es a veces muy dif\u00edcil que te sirvan vino en bares o cafeter\u00edas de zonas productoras espa\u00f1olas (\u00bf).<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Por otra parte cabr\u00eda preguntarse si habr\u00e1 vino en las casas de ciertos de los a s\u00ed mismos llamados cr\u00edticos de vinos o incluso sumilleres o comerciales<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>del ramo \u00bfo incluso gerentes y \u201ct\u00e9cnicos\u201d de consejos reguladores?.<SPAN style=\"mso-spacerun: yes\">  <\/SPAN>Donde seguro no est\u00e1 el vino es en los antros inmensos y lujosamente amueblados donde se toman las decisiones de especular contra la deuda p\u00fablica de ciertos pa\u00edses.<\/FONT><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tanto hablar de vinos y de su presencia aqu\u00ed y all\u00e1; y nunca se me hab\u00eda ocurrido considerar donde no se encuentra el vino y por qu\u00e9. (Esta consideraci\u00f3n viene a prop\u00f3sito del tema tan manido en boca de bodegueros y dem\u00e1s sectores implicados en la producci\u00f3n del vino: que se compra o se consume [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-93","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/comments?post=93"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/posts\/93\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/media?parent=93"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/categories?post=93"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/a-ojo-de-buen-cubero\/wp-json\/wp\/v2\/tags?post=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}