{"id":136,"date":"2009-09-11T10:06:00","date_gmt":"2009-09-11T10:06:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/cautivo\/?p=136"},"modified":"2009-09-11T10:06:00","modified_gmt":"2009-09-11T10:06:00","slug":"feria-verguenza","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/cautivo\/2009\/09\/11\/feria-verguenza\/","title":{"rendered":"Feria de verg\u00fcenza"},"content":{"rendered":"<p>El Ayuntamiento de Logro\u00f1o de Tom\u00e1s Santos acaba de tomar una medida lamentable, injusta y, a todas luces, inexplicable. El Ayuntamiento de Logro\u00f1o de \u00c1ngel Varea se ha lanzado por la pendiente del populismo m\u00e1s desvergonzado,<strong> tomando partido por quien no debe<\/strong>, malutilizando los recursos p\u00fablicos en el peor momento posible. El Ayuntamiento de Logro\u00f1o se equivoca, y coge mi dinero para pagar lo que unos empresarios con la cara muy dura deben, pero no quieren, pagar.<\/p>\n<p>La historia es breve y conocida. Las empresas <strong>Aspe y Asegarce<\/strong>, que dominan el cotarro de la pelota, intentaron coaccionar al Gobierno de La Rioja con una amenaza digna de un capo mafioso: si me obligas a pagar los impuestos que legalmente tengo que pagar, no hago la Feria de San Mateo.<\/p>\n<p><center><IMG src='\/\/static-blogs.larioja.com\/blogfiles\/cautivo\/img_verguenza_small.jpg' id='img_0'><\/center><\/p>\n<p>El Gobierno de La Rioja hizo en esta ocasi\u00f3n lo que ten\u00eda que hacer, decir que la <strong>ley es la ley<\/strong>. Las empresas, con la m\u00e1s pura desverg\u00fcenza, dijeron p\u00fablicamente que ellas lo que buscan es que alguien les pague los tributos. Y lo peor es que lo ha encontrado: el Ayuntamiento de Logro\u00f1o de \u00c1ngel Varea y Tom\u00e1s Santos va a utilizar <strong>el dinero de los logro\u00f1eses<\/strong> para pagar los impuestos que no quieren pagar en La Rioja unas empresas de fuera de La Rioja. Tremendo logro para un Ayuntamiento que se dice <strong>socialista y regionalista<\/strong>.<\/p>\n<p>La Feria de San Mateo de este a\u00f1o ser\u00e1, as\u00ed, <strong>una feria de verg\u00fcenza<\/strong>. El m\u00e1s puro electoralismo populachero, el af\u00e1n de meter el dedo en el ojo del contrario ha cegado al Ayuntamiento, que ha olvidado que se debe a los ciudadanos y a la ley. Ojal\u00e1, sue\u00f1o, les salga la cosa por la culata a todos. Ojal\u00e1 no vaya nadie.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Logro\u00f1o de Tom\u00e1s Santos acaba de tomar una medida lamentable, injusta y, a todas luces, inexplicable. El Ayuntamiento de Logro\u00f1o de \u00c1ngel Varea se ha lanzado por la pendiente del populismo m\u00e1s desvergonzado, tomando partido por quien no debe, malutilizando los recursos p\u00fablicos en el peor momento posible. El Ayuntamiento de Logro\u00f1o [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-136","post","type-post","status-publish","format-standard","hentry","category-cada-viernes"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}