{"id":157,"date":"2010-03-12T19:01:00","date_gmt":"2010-03-12T19:01:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/cautivo\/?p=157"},"modified":"2010-03-12T19:01:00","modified_gmt":"2010-03-12T19:01:00","slug":"nivel-freatico","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/cautivo\/2010\/03\/12\/nivel-freatico\/","title":{"rendered":"Nivel fre\u00e1tico"},"content":{"rendered":"<p>Si es que era <strong>demasiado bonito<\/strong>. El soterramiento hab\u00eda empezado, y todo iba a ser perfecto. La v\u00eda del tren desaparecer\u00eda de la vista, como si nunca hubiera existido, y en su lugar nacer\u00eda una nueva ciudad, am\u00e9n de un cintur\u00f3n verde para que las bicis rodaran y los ni\u00f1os jugaran.<\/p>\n<p>Pero claro, ahora resulta que la realidad es un poco m\u00e1s fea. Y que, parece, el Ministerio sigue empe\u00f1ado en encalomarnos <strong>un soterramiento en forma de ata\u00fad<\/strong>.O sea, que en algunos puntos m\u00e1s que un soterramiento aparecer\u00e1 un caj\u00f3n de 4 metros (una casa de piso y pico de alto, para entendernos) donde antes estaba la v\u00eda al aire libre.<\/p>\n<p>Y ah\u00ed vuelve a aparecer la antigua cantinela logro\u00f1esa. No se puede soterrar a cota cero (o sea, haciendo desaparecer la v\u00eda del todo) porque <strong>el nivel fre\u00e1tico est\u00e1 muy alto<\/strong>.O sea, porque echas la pala y aparece agua subterr\u00e1nea. Que no se puede cavar m\u00e1s, vamos.<\/p>\n<div style=\"text-align:center\"><IMG src='\/\/static-blogs.larioja.com\/blogfiles\/cautivo\/freatico.jpg' id='img_0'><\/div>\n<p>Esto, dicho en 1930, hubiera tenido su sentido. Pero, \u00bfsaben?, estamos en el 2010. Estamos en un siglo en el que un tren pasa bajo el Canal de la Mancha. Que como nivel fre\u00e1tico, ya es.<\/p>\n<p>Quiz\u00e1 les parezca ex\u00f3tico, y una de esas obras del mundo mundial que s\u00f3lo se dan una vez en la vida. Si quieren, nos fijamos un poco m\u00e1s cerca, <strong>en el mismo Bilbao<\/strong>: all\u00ed hay un tren subterr\u00e1neo \u2013metro, le llaman\u2013 que cruza la r\u00eda. Y dos veces. Que yo no s\u00e9 cu\u00e1nta agua subterr\u00e1nea hay bajo Logro\u00f1o. Pero tanta como en la r\u00eda de Bilbao&#8230;<\/p>\n<p>Nos la est\u00e1n dando con queso, y no ser\u00e1 por no advertirlo. Porque la cuesti\u00f3n es, como siempre, el dinero. <strong>Hacerse, se puede hacer<\/strong>, aunque ser\u00e1 m\u00e1s caro. Pero conviene pensarlo: la oportunidad para la ciudad s\u00f3lo pasar\u00e1 una vez.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Si es que era demasiado bonito. El soterramiento hab\u00eda empezado, y todo iba a ser perfecto. La v\u00eda del tren desaparecer\u00eda de la vista, como si nunca hubiera existido, y en su lugar nacer\u00eda una nueva ciudad, am\u00e9n de un cintur\u00f3n verde para que las bicis rodaran y los ni\u00f1os jugaran. Pero claro, ahora resulta [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-157","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/157\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/media?parent=157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/categories?post=157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/tags?post=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}