{"id":179,"date":"2010-09-10T17:16:00","date_gmt":"2010-09-10T17:16:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/cautivo\/?p=179"},"modified":"2010-09-10T17:16:00","modified_gmt":"2010-09-10T17:16:00","slug":"cenan-italianos","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/cautivo\/2010\/09\/10\/cenan-italianos\/","title":{"rendered":"\u00bfCenan los italianos?"},"content":{"rendered":"<p>\u00bfCenan los italianos? Es una pregunta de singular importancia, se lo prometo. \u00bfComen los italianos? Fuera de casa, aclaro. <strong>\u00bfHay restaurantes en Italia?<\/strong> La pregunta no es tan tonta como, reconozco, parece. Pero quiz\u00e1 requiera una explicaci\u00f3n.<\/p>\n<p>En Italia no se fuma. En casa de cada uno, o en la calle, s\u00ed. Pero en los lugares p\u00fablicos del tipo que sea, no. No hay trattoria con cigarrillo, <strong>no hay bar<\/strong> con cenicero. Hace ya a\u00f1os que los transalpinos prohibieron el humo en lugares p\u00fablicos y, sin embargo, oh prodigio, sigue habiendo bares.<\/p>\n<p>Porque si uno oye a los hosteleros riojanos, uno dir\u00eda que <strong>el armaged\u00f3n se acerca<\/strong>. Pr\u00f3ximamente, Dios mediante, se prohibir\u00e1 totalmente fumar en los locales p\u00fablicos espa\u00f1oles. La cosa es bastante l\u00f3gica: el humo del tabaco es malo, y punto. Y aunque en su casa cada uno es libre de apestar a los suyos, en los locales p\u00fablicos esa libertad se acaba.<\/p>\n<div style=\"text-align:center\"><IMG src='\/\/static-blogs.larioja.com\/blogfiles\/cautivo\/tabaco.jpg' id='img_0'><\/div>\n<p>Pero dicen los hosteleros que eso les va a hacer perder dinero. La primera reacci\u00f3n deber\u00eda ser decir \u00aby qu\u00e9\u00bb.O sea, que aunque los hosteleros <strong>se arruinaran en racimos<\/strong>, el beneficio para la salud lo merecer\u00eda. Sobre todo para los hosteleros, curiosamente, a no ser que prefieran su cartera a sus pulmones.<\/p>\n<p>Pero es que es extremadamente dudoso que vayan a perder ese dinero. \u00bfDe verdad creen que la gente va a dejar de ir a bares o restaurantes porque no pueda encender su cigarro? Extra\u00f1o concepto tienen de su negocio: o sea, <strong>ellos sirven bebidas y comidas, pero la gente en realidad va a fumar<\/strong>.<\/p>\n<p>No se preocupen, se\u00f1ores hosteleros. Los italianos cenan. Quiz\u00e1 antes del postre se levanten a echarse su pitillito en la acera. Pero luego vuelven. As\u00ed que dejen de quejarse&#8230; y pongan <strong>un cenicero en la puerta<\/strong>.<\/P><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfCenan los italianos? Es una pregunta de singular importancia, se lo prometo. \u00bfComen los italianos? Fuera de casa, aclaro. \u00bfHay restaurantes en Italia? La pregunta no es tan tonta como, reconozco, parece. Pero quiz\u00e1 requiera una explicaci\u00f3n. En Italia no se fuma. En casa de cada uno, o en la calle, s\u00ed. Pero en los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-179","post","type-post","status-publish","format-standard","hentry","category-cada-viernes"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/cautivo\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}