{"id":1522,"date":"2015-05-25T11:01:45","date_gmt":"2015-05-25T10:01:45","guid":{"rendered":"http:\/\/blogs.larioja.com\/chucherias\/?p=1522"},"modified":"2015-05-25T11:01:45","modified_gmt":"2015-05-25T10:01:45","slug":"asalto-en-la-calle","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/chucherias\/2015\/05\/25\/asalto-en-la-calle\/","title":{"rendered":"Asalto en la calle"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/05\/terraza.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1523\" title=\"terraza\" src=\"\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/05\/terraza.gif\" alt=\"\" width=\"581\" height=\"318\" \/><\/a><\/p>\n<p style=\"text-align: center;\">El <strong>yayo Tasio<\/strong> cay\u00f3 anoche en la cuenta de que se hab\u00eda quedado sin las pastillas de dormir y se aventur\u00f3 a salir de casa a \u00faltima hora para llegarse a la farmacia de guardia. <strong>Nada m\u00e1s poner un pie en la calle le atacaron<\/strong>. Lo peor no es que intentaran abusar de un viejo indefenso y enclenque sino que el agresor fuera un conocido. El asaltante era el mismo velador que lleva a\u00f1os instalado a la puerta del portal en cuanto asomaba una miaja de sol y en los \u00faltimos tiempos ya le da igual que llueva o truene para apoderarse del espacio p\u00fablico. Al principio era modosito. Ocupaba un pu\u00f1ado de baldosas y hasta le daba una pizca de color al barrio y una alegr\u00eda a la caja del bar. De pronto, empez\u00f3 a medrar. Las mesas se reprodujeron como conejos, las sillas de pl\u00e1stico mutaron en modernos asientos met\u00e1licos que chirr\u00edan cada vez que se desplazan. <strong>Brotaron sombrillas, parieron estufas de butano, se levantaron empalizadas de metacrilato<\/strong>. Esa misma terracita en origen amable e inofensiva fue la que atac\u00f3 al abuelo. Le acorral\u00f3 sin previo aviso. Tasio intent\u00f3 zafarse, pero la clientela repanchingada sobre los cojines le cerr\u00f3 el paso. Busc\u00f3 huir por alg\u00fan fino desfiladero de Term\u00f3pilas militarizado de cubatas y ca\u00f1as de cerveza. Imposible. No tuvieron piedad de su boina ni sus prisas por llegar a la botica. El velador le hab\u00eda acorralado. Para salir vivo y suplir los somn\u00edferos, pens\u00f3 rendirse y pedir all\u00ed mismo una infusi\u00f3n de tila y valeriana. Desisti\u00f3. No hab\u00eda un solo asiento libre.<\/p>\n<p style=\"text-align: center;\">Fotograf\u00eda: <strong>Sonia Tercero<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El yayo Tasio cay\u00f3 anoche en la cuenta de que se hab\u00eda quedado sin las pastillas de dormir y se aventur\u00f3 a salir de casa a \u00faltima hora para llegarse a la farmacia de guardia. Nada m\u00e1s poner un pie en la calle le atacaron. Lo peor no es que intentaran abusar de un viejo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[169,187,1777,1878,1936],"class_list":["post-1522","post","type-post","status-publish","format-standard","hentry","category-la-rioja","tag-asalto","tag-atraco","tag-terraza","tag-velador","tag-yayo-tasio"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts\/1522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/comments?post=1522"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts\/1522\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/media?parent=1522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/categories?post=1522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/tags?post=1522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}