{"id":1589,"date":"2015-10-21T18:14:33","date_gmt":"2015-10-21T17:14:33","guid":{"rendered":"http:\/\/blogs.larioja.com\/chucherias\/?p=1589"},"modified":"2015-10-21T18:14:33","modified_gmt":"2015-10-21T17:14:33","slug":"aprender-a-leer","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/chucherias\/2015\/10\/21\/aprender-a-leer\/","title":{"rendered":"Aprender a leer"},"content":{"rendered":"<p><a href=\"\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/10\/encuesta-del-CIS-2015-teri.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1590\" title=\"plantillailus3\" src=\"\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/10\/encuesta-del-CIS-2015-teri.jpg\" alt=\"cis\" width=\"573\" height=\"719\" srcset=\"https:\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/10\/encuesta-del-CIS-2015-teri.jpg 680w, https:\/\/static-blogs.larioja.com\/chucherias\/wp-content\/uploads\/sites\/7\/2015\/10\/encuesta-del-CIS-2015-teri-239x300.jpg 239w\" sizes=\"auto, (max-width: 573px) 100vw, 573px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Los sondeos son esos artefactos que los expertos en demoscopia elaboran sesudamente durante meses de cocci\u00f3n y trabajo de campo y los periodistas resumimos en un titular. Un retrato panor\u00e1mico pintado a brochazos con pinceladas de un pu\u00f1adito de encuestados que los partidos dicen ignorar confiados en s\u00ed mismos, aunque <strong>en la intimidad de sus salas de m\u00e1quinas<\/strong> los desmenuzan hasta la \u00faltima mol\u00e9cula para afinar el tiro electoral. El <strong>CIS<\/strong> tiene la virtud y el defecto de abrir tanto el abanico de opciones que es capaz de satisfacer el ego de cualquiera. Al menos, de cualquiera que se empecine en <strong>mirarse al ombligo<\/strong>. En la pregunta 19 del \u00faltimo informe que pulsa el estado de opini\u00f3n tras las elecciones auton\u00f3micas de mayo que quebraron la mayor\u00eda absoluta de los populares, el 14,7% se decanta por un gobierno en solitario del <a title=\"pp\" href=\"https:\/\/twitter.com\/lariojapp\" rel=\"external nofollow\">PP<\/a>, el 19,3%  prefiere que se coaligue con <a title=\"Ciudadanos\" href=\"https:\/\/twitter.com\/cslarioja\" rel=\"external nofollow\">Ciudadanos <\/a>y el 28,3% se inclina por un <strong>tripartito entre PSOE, Podemos y C\u00b4s<\/strong>. Un escenario suficientemente multicolor para que todos los implicados puedan concluir estrangulando la estad\u00edstica que el otro declina, empe\u00f1ados en ignorar la \u00fanica certeza: casi la mitad de los riojanos opta por un poder compartido lejos e posturas hegem\u00f3nicas que, m\u00e1s all\u00e1 de combinaciones, favorezca la pluralidad y, de paso, convenza a los que un poco m\u00e1s arriba del cuestionario reconocen abrumadoramente que no votan porque est\u00e1n <strong>hartos de la pol\u00edtica o desconf\u00edan de las sigla<\/strong>s. De todas las siglas.<\/p>\n<p style=\"text-align: center;\">Imagen: <strong>J.A. Salazar<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los sondeos son esos artefactos que los expertos en demoscopia elaboran sesudamente durante meses de cocci\u00f3n y trabajo de campo y los periodistas resumimos en un titular. Un retrato panor\u00e1mico pintado a brochazos con pinceladas de un pu\u00f1adito de encuestados que los partidos dicen ignorar confiados en s\u00ed mismos, aunque en la intimidad de sus [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[425,430,682,701,1467,1483,1525],"class_list":["post-1589","post","type-post","status-publish","format-standard","hentry","category-la-rioja","tag-cis","tag-ciudadanos","tag-elecciones","tag-encuesta","tag-podemos","tag-pp","tag-psoe"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts\/1589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/comments?post=1589"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/posts\/1589\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/media?parent=1589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/categories?post=1589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/chucherias\/wp-json\/wp\/v2\/tags?post=1589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}