{"id":127,"date":"2007-05-03T10:05:16","date_gmt":"2007-05-03T10:05:16","guid":{"rendered":"http:\/\/blogs.larioja.com\/elbisturi\/?p=127"},"modified":"2007-05-03T10:05:16","modified_gmt":"2007-05-03T10:05:16","slug":"una-estafa","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/elbisturi\/2007\/05\/03\/una-estafa\/","title":{"rendered":"Una estafa"},"content":{"rendered":"<p><DIV class=p-SAP id=story-texto>Ya en sus \u00faltimos a\u00f1os mi madre aseguraba que la vida es una estafa. La primera vez que se lo o\u00ed soltar yo todav\u00eda acumulaba m\u00e1s expectativas que experiencia, albergaba m\u00e1s ilusi\u00f3n que frustraci\u00f3n y dispon\u00eda de m\u00e1s futuro que pasado y me alarm\u00f3 tal s\u00edntoma de amargo desenga\u00f1o precisamente en ella. Que quien trat\u00f3 de inculcarnos desde peque\u00f1itos tantos buenos valores de los que andaba sobrada (bondad, honradez, compasi\u00f3n, austeridad, optimismo, rectitud, tes\u00f3n) llegara a semejante conclusi\u00f3n era perturbador y el impacto de aquel primer cascote desprendido de la fachada de su vida hizo tambalear los andamios de la m\u00eda. Ahora que ya tengo m\u00e1s andado que por andar, acumulo m\u00e1s decepciones que satisfacciones y rumio menos proyectos que fracasos, entiendo por qu\u00e9 lo dec\u00eda. Pues qu\u00e9 es, sino una estafa, que te cristianen con el cord\u00f3n a\u00fan colgando para eludir un limbo que finalmente no existe, como dejar\u00e1n oficialmente de existir alg\u00fan d\u00eda ese cielo, ese infierno y ese Dios que aterrorizaron nuestra pecadora adolescencia. A ver si no lo fueron tant\u00edsimas tardes desperdiciadas aprendiendo el franc\u00e9s (es un idioma), tan in\u00fatil como casi todas las dem\u00e1s asignaturas superadas durante d\u00e9cadas. Qu\u00e9 es m\u00e1s que un timo perder los mejores veranos de tu vida embruteci\u00e9ndote en un cuartel para adiestrarte en la defensa de una patria que resulta estar en Afganist\u00e1n. O casarte impoluto a los veintitr\u00e9s por la iglesia y con banquete para disfrutar al final de los mism\u00edsimos derechos que las parejas de lecho. O echar a perder la infancia en un siniestro internado porque para chicos en Haro s\u00f3lo hab\u00eda un instituto laboral donde enseban el manejo del destornillador, la gubia, el serrucho y la escofina, que es lo que uno ha terminado empu\u00f1ando despu\u00e9s de siete a\u00f1os de bachiller y nueve m\u00e1s entre carrera y especialidad, con la diferencia de que una mesa no te sienta en el banquillo si cree que la has dejado coja. Y qu\u00e9 calificativo merece cotizar a la Seguridad Social durante treinta a\u00f1os para que te salgan con que ya veremos si llega para tu pensi\u00f3n y que mejor te vas haciendo un plan. Qu\u00e9 es, en fin, el sal\u00f3n-comedor de los buenos ratos sino un pante\u00f3n familiar en ciernes. La vida es un encadenamiento de embelecos y desencantos que comienzan en la tercera d\u00e9cada y van creciendo hasta convertirse en ese estado permanente de infortunio que a menudo es la vejez (\u00abel precio que hay que pagar por haber vivido\u00bb), cuando el edificio de la vida, levantado con tanto esfuerzo y tantas ilusiones, se arruina hasta desmoronarse por completo. Una estafa. Qu\u00e9 raz\u00f3n llevabas, Finita. Como siempre.<\/DIV><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya en sus \u00faltimos a\u00f1os mi madre aseguraba que la vida es una estafa. La primera vez que se lo o\u00ed soltar yo todav\u00eda acumulaba m\u00e1s expectativas que experiencia, albergaba m\u00e1s ilusi\u00f3n que frustraci\u00f3n y dispon\u00eda de m\u00e1s futuro que pasado y me alarm\u00f3 tal s\u00edntoma de amargo desenga\u00f1o precisamente en ella. Que quien trat\u00f3 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-127","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/127\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/media?parent=127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/categories?post=127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/tags?post=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}