{"id":17,"date":"2005-02-03T18:59:14","date_gmt":"2005-02-03T18:59:14","guid":{"rendered":"http:\/\/blogs.larioja.com\/elbisturi\/?p=17"},"modified":"2005-02-03T18:59:14","modified_gmt":"2005-02-03T18:59:14","slug":"la-euroconstitucion-y-gases-del-vecino","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/elbisturi\/2005\/02\/03\/la-euroconstitucion-y-gases-del-vecino\/","title":{"rendered":"La Euroconstituci\u00f3n y los Gases del Vecino"},"content":{"rendered":"<p>En este pa\u00eds, desde Franco a Zetap\u00e9, los referendos se han utilizado o para met\u00e9rsela doblada al nosabenocontesta o para torcer la opini\u00f3n de quien lo que sabe no le gusta al preguntador. Quiz\u00e1 s\u00f3lo las dos manipulaciones de Su\u00e1rez (1976 y 1978) fueron claramente beneficiosas para todos, pues liquidaron el franquismo dando paso a un Estado de derecho. Pero \u00e9ste de la llamada Constituci\u00f3n Europea me recuerda a posteriores plebiscitos de apoyo al gobierno de casa aprovechando que el Danubio pasa por Budapest, y ya s\u00f3lo por eso el cuerpo me pide votar no el 20-F. Pero hay otra raz\u00f3n principal.<br \/>\nSe nos machaca con que este Tratado es un paso m\u00e1s en la construcci\u00f3n europea. Pues hablando de obras no pongamos el tejado sobre cimientos sin fraguar o el edificio acabar\u00e1 vini\u00e9ndose abajo. Y uno de esos pilares flojos es esa Constituci\u00f3n nuestra tan superada, cuyo art\u00edculo 47 consagra el derecho de todos los espa\u00f1oles a una vivienda digna y condena expresamente la especulaci\u00f3n del suelo. Sin embargo, los afortunados propietarios de fincas a punto de ser engullidas por el crecimiento urbano siguen frot\u00e1ndose las manos ante la porrada de millones gracias a los cuales la repercusi\u00f3n del astron\u00f3mico precio del solar en el del piso superar\u00e1 al de la edificaci\u00f3n, con lo que un mont\u00f3n de familias tendr\u00e1n que hipotecar la mitad de los ingresos de toda su vida para que una sola se forre con el pelotazo.<br \/>\nPero es que, adem\u00e1s de car\u00edsimas, nuestras viviendas est\u00e1n tan mal hechas que podemos o\u00edr hasta los gases que por v\u00eda oral o rectal tengan a bien expeler nuestros vecinos. Y esto ocurre igual con gobiernos de derecha que de izquierda incapaces de limitar el precio del suelo destinado a satisfacer una primera necesidad que es adem\u00e1s un derecho constitucional b\u00e1sico. As\u00ed que para qu\u00e9 queremos una Super Carta Magna si la de aqu\u00ed es papel mojado. Menos construcci\u00f3n europea y m\u00e1s construcci\u00f3n espa\u00f1ola, riojana o najerina digna, asequible y aislada como Dios manda. C\u00f3mo no vamos a sentir los pedos si los tabiques son una mierda, aunque la estemos pagando a precio de oro. Y contentos, que a\u00fan no los olemos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En este pa\u00eds, desde Franco a Zetap\u00e9, los referendos se han utilizado o para met\u00e9rsela doblada al nosabenocontesta o para torcer la opini\u00f3n de quien lo que sabe no le gusta al preguntador. Quiz\u00e1 s\u00f3lo las dos manipulaciones de Su\u00e1rez (1976 y 1978) fueron claramente beneficiosas para todos, pues liquidaron el franquismo dando paso a [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-17","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/17\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/media?parent=17"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/categories?post=17"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/tags?post=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}