{"id":175,"date":"2009-01-08T09:44:00","date_gmt":"2009-01-08T09:44:00","guid":{"rendered":"http:\/\/blogs.larioja.com\/elbisturi\/?p=175"},"modified":"2009-01-08T09:44:00","modified_gmt":"2009-01-08T09:44:00","slug":"la-vida-sana","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/elbisturi\/2009\/01\/08\/la-vida-sana\/","title":{"rendered":"La vida sana"},"content":{"rendered":"\n<p class=\"MsoNormal\"><span lang=\"ES\">Llevar una vida sana no consiste en hacer ejercicio f\u00edsico compulsivamente. Todos los a\u00f1os mueren deportistas con las zapatillas puestas y millones de aficionados sufren lesiones, muchas con secuelas invalidantes, mientras se esfuerzan en mejorar su salud. La vida sana tampoco es el resultado de obsesionarse con mortificadoras dietas que proh\u00edben lo sabroso en favor de lo ins\u00edpido; se pueden ingerir 25 huevos diarios durante d\u00e9cadas sin modificarse la tasa de colesterol, la cual por cierto carece de valor predictivo del riesgo de ataque card\u00edaco, como tampoco hay evidencia cient\u00edfica de relaci\u00f3n causal entre consumo de grasas y enfermedad cardiovascular. Una vida sana no deber\u00eda proscribir el consumo de alcohol, asequible analg\u00e9sico de las miserias cotidianas que s\u00ed ejerce un efecto cardioprotector, y tampoco est\u00e1 re\u00f1ida con el consumo de tabaco: muchos nonagenarios mueren fumando y ni los no fumadores est\u00e1n a salvo del c\u00e1ncer de pulm\u00f3n, entre otros. La vida sana, qu\u00e9 quieren, no depende de la eliminaci\u00f3n de \u201cfactores de riesgo\u201d o de \u201ch\u00e1bitos no saludables\u201d involucrados en lesiones y enfermedades; no se necesita un cribado masivo de esos con que los gobernantes se las dan de benefactores preocupados por la salud de su pueblo para saber que el permiso de conducir, verbigracia, es un indiscutible factor de riesgo de sufrir accidentes de tr\u00e1fico. Entonces, \u00bflo suprimimos? La vida sana, en fin, no es fruto del obsesivo culto al cuerpo de las sociedades ricas bajo el lema: \u201cYa que no podemos ser felices, estemos sanos al menos\u201d, pues ni eso se sostiene dado que tambi\u00e9n los m\u00e9dicos, vegetarianos, delgados, abstemios, deportistas, gur\u00fas del estilo de vida saludable y epidemi\u00f3logos acabamos palmando. Una vida sana, creo yo, es la que transcurre en armon\u00eda con el medio que nos ha tocado en suerte. Vivir sanamente es desempe\u00f1ar correctamente los roles familiar, social y laboral con responsabilidad, competencia, honestidad, lealtad, afecto, respeto y generosidad. Y, desde luego, disfrutar plenamente de los d\u00edas que nos queden sin miedo a contraer una enfermedad seguramente distinta de la que nos matar\u00e1. Lo cual no es incompatible con criar michelines, hidratarse con cerveza, inflarse a panchitos, tumbarse en el sof\u00e1 a ver f\u00fatbol o escuchar \u00f3pera, fumarse un puro tan lenta y ceremoniosamente como si fuese el \u00faltimo, practicar yoga ib\u00e9rico por todo deporte e incluso con padecer una fastidiosa enfermedad cr\u00f3nica. Lo dem\u00e1s son modas, supersticiones, neuras y paternalismo estatal ejercido a trav\u00e9s de una medicina oficial totalitaria, coercitiva e inculpatoria, basada en manipulaciones estad\u00edsticas que con el interesado aval de la burocracia sanitaria mundial permiten a la industria del estilo-de-vida-saludable hacer su agosto medicalizando a millones de personas sin m\u00e1s enfermedad que el p\u00e1nico a enfermar. No s\u00e9 si me explico.<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Llevar una vida sana no consiste en hacer ejercicio f\u00edsico compulsivamente. Todos los a\u00f1os mueren deportistas con las zapatillas puestas y millones de aficionados sufren lesiones, muchas con secuelas invalidantes, mientras se esfuerzan en mejorar su salud. La vida sana tampoco es el resultado de obsesionarse con mortificadoras dietas que proh\u00edben lo sabroso en favor [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-175","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/elbisturi\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}