{"id":2445,"date":"2018-04-27T17:31:23","date_gmt":"2018-04-27T15:31:23","guid":{"rendered":"http:\/\/blogs.larioja.com\/eltiempo\/?p=2445"},"modified":"2018-04-27T18:48:39","modified_gmt":"2018-04-27T16:48:39","slug":"fin-de-semana-y-puente-de-mayo-revuelto-e-inestable","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/eltiempo\/2018\/04\/27\/fin-de-semana-y-puente-de-mayo-revuelto-e-inestable\/","title":{"rendered":"Fin de semana y Puente de Mayo revuelto e inestable"},"content":{"rendered":"<p>Todo apunta a que se van cumpliendo los refranes y si\u00a0 &#8221; Nieve en la luna de Octubre&#8230;..siete lunas cubre &#8221; no va a ser menos cierto que &#8220;Hasta el 40 de mayo no te quites el sayo&#8221;<\/p>\n<p>De nuevo se producen cambios en las capas m\u00e1s altas de la atm\u00f3sfera una marcada <strong>ondulaci\u00f3n en la Corriente en Chorro<\/strong> favorece la llegada de aire fr\u00edo polar en forma de <strong>vaguad<\/strong>a, aire muy inestable que va a favorecer el crecimiento de nubosidad y el descenso de temperaturas<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" class=\"aligncenter size-full wp-image-2446\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/JET-2.jpg\" alt=\"&quot;&lt;\/p\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/JET-2.jpg 960w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/JET-2-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/JET-2-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Originar\u00e1 este aire fr\u00edo borrascas en superficie con frentes asociados que van a favorecer la llegada de una masa de aire polar mar\u00edtima de car\u00e1cter fr\u00edo y h\u00famedo que aparte de favoerecer el crecimiento de nubosidad va a traer consigo un descenso de temperaturas<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2447 size-medium\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/850-650x433.jpg\" alt=\"Mapa de altura geopotencial 850hPa.Meteosojuela\" width=\"650\" height=\"433\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/850-650x433.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/850-768x512.jpg 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/850-1024x683.jpg 1024w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/850.jpg 1600w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Hasta 10\u00baC pueden descender las temperaturas respecto a las de d\u00edas pasados lo que traer\u00e1 consigo la aparici\u00f3n de nuevo de la nieve en las cumbres de la Ib\u00e9rica riojana<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2448 size-medium\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/ENSEMBLE1-650x488.jpg\" alt=\"Ensemble ciudad de Logro\u00f1o.Meteosojuela\" width=\"650\" height=\"488\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/ENSEMBLE1-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/ENSEMBLE1-768x576.jpg 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/ENSEMBLE1.jpg 960w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>As\u00ed que durante el fin de semana y el puente de Mayo se espera un tiempo revuelto e inestable, con nubosidad abundante cuando lleguen los frentes y l\u00edneas de inestabilidad, mejorando tras su paso.<\/p>\n<p>Se van a producir precipitaciones en forma de chubascos y de tormentas que localmente pueden ser intensas y venir acompa\u00f1adas de granizo. Ser\u00e1 m\u00e1s probables en \u00e1reas de monta\u00f1a.<\/p>\n<p>Las temperaturas en progresivo descenso por lo que la nieve aparecer\u00e1 cada vez en cotas m\u00e1s bajas, pudi\u00e9ndo darse tambi\u00e9n heladas en zonas altas.<\/p>\n<p>As\u00ed que chubasqueros y algo de ropa de abrigo para estos pr\u00f3ximos d\u00edas<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2451 size-medium\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA2704rioja-1-650x488.jpg\" alt=\"Tendencia del tiempo en La Rioja el fin de semana.Meteosojuela\" width=\"650\" height=\"488\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA2704rioja-1-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA2704rioja-1-768x576.jpg 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA2704rioja-1.jpg 960w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2456 size-medium\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA-2704rioja-650x488.jpg\" alt=\"tendencia-finde-semana-2704rioja\" width=\"650\" height=\"488\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA-2704rioja-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA-2704rioja-768x576.jpg 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/04\/TENDENCIA-FINDE-SEMANA-2704rioja.jpg 960w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><br \/>\nOs recuerdo que ten\u00e9is m\u00e1s informaci\u00f3n en la<\/p>\n<div id=\"Image1\" class=\"widget Image\">\n<h2 style=\"text-align: center;\"><a href=\"http:\/\/www.meteosojuela.es\" rel=\"external nofollow\"> \u00a1\u00a1 NUEVA WEB !!<\/a><\/h2>\n<div class=\"widget-content\" style=\"text-align: center;\"><a href=\"https:\/\/www.meteosojuela.es\/ \" target=\"_blank\"> <img loading=\"lazy\" decoding=\"async\" id=\"Image1_img\" style=\"visibility: visible;\" src=\"https:\/\/www.meteosojuela.es\/logrowebcam2_TVL.jpg?1524236842986\" alt=\"Webcam Logro\u00f1o\" width=\"1280\" height=\"480\" \/><br \/>\n<\/a>La informaci\u00f3n del tiempo en La Rioja en el momento<\/div>\n<div class=\"widget-content\" style=\"text-align: center;\">Datos de Estaciones Meteorol\u00f3gicas con Webcams en tiempo real 24h<\/div>\n<div class=\"widget-content\" style=\"text-align: center;\">Previsiones diarias, semanales, fin de semana, mensuales y estacionales<\/div>\n<div class=\"widget-content\" style=\"text-align: center;\">Seguimiento de situaciones<\/div>\n<div class=\"widget-content\" style=\"text-align: center;\">Fotos, videos y mucho m\u00e1s en<\/div>\n<div class=\"widget-content\" style=\"text-align: center;\"><a href=\"http:\/\/www.meteosojuela.es\" rel=\"external nofollow\"><strong><span style=\"font-size: 18pt; color: #000000;\">www.meteosojuela.es<\/span><\/strong><\/a><\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Todo apunta a que se van cumpliendo los refranes y si\u00a0 &#8221; Nieve en la luna de Octubre&#8230;..siete lunas cubre &#8221; no va a ser menos cierto que &#8220;Hasta el 40 de mayo no te quites el sayo&#8221; De nuevo se producen cambios en las capas m\u00e1s altas de la atm\u00f3sfera una marcada ondulaci\u00f3n en [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":2452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[686,309,333,499,581],"class_list":["post-2445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-previsiones-2","tag-fin-de-semana","tag-inestable","tag-larioja","tag-puente-de-mayo","tag-tiempo"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/comments?post=2445"}],"version-history":[{"count":6,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2445\/revisions"}],"predecessor-version":[{"id":2459,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2445\/revisions\/2459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media\/2452"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media?parent=2445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/categories?post=2445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/tags?post=2445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}