{"id":2740,"date":"2018-09-14T18:08:24","date_gmt":"2018-09-14T16:08:24","guid":{"rendered":"http:\/\/blogs.larioja.com\/eltiempo\/?p=2740"},"modified":"2018-09-14T18:08:24","modified_gmt":"2018-09-14T16:08:24","slug":"comienzan-las-fiestas-de-san-mateo","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/eltiempo\/2018\/09\/14\/comienzan-las-fiestas-de-san-mateo\/","title":{"rendered":"Comienzan las fiestas de San Mateo"},"content":{"rendered":"<p>Y la verdad es que desde el punto de vista meteorol\u00f3gico no pueden tener mejor aspaecto.<\/p>\n<p>No quitabamos el ojo durante la semana a la <strong>DANA (Gota Fr\u00eda)<\/strong> situada en el sur peninsular donde esta dejando fuertes tormentas e inundaciones y que esperabamos que se acercase hacia nuestra regi\u00f3n como al final no ocurri\u00f3. As\u00ed que vivimos en una prolongaci\u00f3n del verano con cielos poco nubosos y temperaturas por encima de lo habitual para esta \u00e9poca del a\u00f1o.<\/p>\n<p>Y as\u00ed vamos a continuar, con<strong> estabilidad en capas altas<\/strong> y <strong>altas presiones en superficie<\/strong> extendi\u00e9ndose desde el ATl\u00e1ntico a Centroeuropa y abarcando todo el norte peninsular incluida nuestra regi\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2741\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SUP.jpg\" alt=\"Modelos de presi\u00f3n en superficie. Meteosojuela\" width=\"960\" height=\"720\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SUP.jpg 960w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SUP-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SUP-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>As\u00ed que este fin de semana y comienzo de fiestas esperamos<strong> cielos poco nubosos o despejados<\/strong> , con vientos que ir\u00e1n rolando <strong>del NNW al SSE<\/strong>, vientos c\u00e1lidos que har\u00e1n <strong>subir las temperaturas<\/strong> y que pueden incluso alcanzar los 30\u00baC en el valle, claramente por encima de lo habitual para esta \u00e9poca del a\u00f1o.<\/p>\n<p>Como mucho podremos ver algunas <strong>nubes bajas a primeras horas<\/strong> en el Oeste de la regi\u00f3n que se disipar\u00e1n r\u00e1pidamente. A lo largo del d\u00eda <strong>nubes altas dispersas<\/strong> y <strong>de evoluci\u00f3n<\/strong> en \u00e1reas de la Ib\u00e9rica donde el domingo por la tarde podr\u00edan dejar <strong>algunas tormentas<\/strong>, peor a\u00fan as\u00ed en general disfrutaremos de un &#8220;veraniego&#8221; comienzo de fiestas<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2742\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA1409lr.jpg\" alt=\"Tendencia del tiempo en La Rioja fin de semana.Meteosojuela\" width=\"960\" height=\"720\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA1409lr.jpg 960w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA1409lr-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA1409lr-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2743\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA-1409lr.jpg\" alt=\"Tendencia del tiempo en La Rioja fin de semana.Meteosojuela\" width=\"960\" height=\"720\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA-1409lr.jpg 960w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA-1409lr-650x488.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/TENDENCIA-FINDE-SEMANA-1409lr-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Y el resto de d\u00edas de fiestas de San Mateo.. \u00bfqu\u00e9 podemos esperar?<\/p>\n<p>Todo parece indicar que van a ser unas<strong> fiestas tranquilas con un ambiente c\u00e1lido<\/strong>. A mediados de semana se puede <strong>inestabilizar<\/strong> algo la situaci\u00f3n por lo que ver\u00edamos <strong>m\u00e1s nubosidad<\/strong> con posibilidad de <strong>algunas tormentas<\/strong> de tarde y ya a finales de semana s\u00ed que se podr\u00eda producir un<strong> descenso de temperatura<\/strong>s por la entrada de <strong>vientos del NW<\/strong> que dejar\u00edan nubosidad y alguna precipitaci\u00f3n d\u00e9bil, si bien es cierto que no todos los modelos se inclinan por ello.<\/p>\n<p>Os dejo aqui nas infograf\u00edas actualizadas<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2744\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SAN-MATEO14.jpg\" alt=\"El tiempo en las fiestas de San Mateo por Jose Calvo de Meteosojuela\" width=\"1280\" height=\"720\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SAN-MATEO14.jpg 1280w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SAN-MATEO14-650x366.jpg 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SAN-MATEO14-768x432.jpg 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/SAN-MATEO14-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2745\" src=\"\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/14.png\" alt=\"El tiempo en las fiestas de San Mateo por Jose Calvo de Meteosojuela\" width=\"1283\" height=\"743\" srcset=\"https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/14.png 1283w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/14-650x376.png 650w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/14-768x445.png 768w, https:\/\/static-blogs.larioja.com\/eltiempo\/wp-content\/uploads\/sites\/39\/2018\/09\/14-1024x593.png 1024w\" sizes=\"auto, (max-width: 1283px) 100vw, 1283px\" \/><\/p>\n<p>Todas estas previsiones las iremos actualizando en la<\/p>\n<div id=\"Image1\" class=\"widget Image\" style=\"text-align: center;\">\n<h2 style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><a href=\"http:\/\/www.meteosojuela.es\/\" rel=\"external nofollow\">\u00a1\u00a1 NUEVA WEB !!<\/a><\/span><\/h2>\n<p>&nbsp;<\/p>\n<div class=\"widget-content\" style=\"text-align: center;\"><span style=\"font-size: large;\"><a href=\"https:\/\/www.meteosojuela.es\/\" target=\"_blank\" rel=\"external nofollow\"> <img loading=\"lazy\" decoding=\"async\" id=\"Image1_img\" style=\"visibility: visible;\" src=\"https:\/\/www.meteosojuela.es\/logrowebcam2_TVL.jpg?1524236842986\" alt=\"Webcam Logro\u00f1o\" width=\"640\" height=\"480\" \/> <\/a><br \/>\nLa informaci\u00f3n del tiempo en La Rioja en el momento<\/span><\/div>\n<p style=\"text-align: center;\"><span style=\"font-size: large;\">Datos de Estaciones Meteorol\u00f3gicas con Webcams en tiempo real 24h<\/span><\/p>\n<div class=\"widget-content\" style=\"text-align: center;\"><span style=\"font-size: large;\">Previsiones diarias, semanales, fin de semana, mensuales y estacionales<\/span><\/div>\n<div class=\"widget-content\" style=\"text-align: center;\"><span style=\"font-size: large;\">Seguimiento de situaciones<\/span><\/div>\n<div class=\"widget-content\" style=\"text-align: center;\"><span style=\"font-size: large;\">Fotos, videos y mucho m\u00e1s en<\/span><\/div>\n<div class=\"widget-content\" style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><span style=\"color: red;\"><a href=\"http:\/\/www.meteosojuela.es\/\" rel=\"external nofollow\"><b><span style=\"color: black;\">www.meteosojuela.es<\/span><\/b><\/a><\/span><\/span><\/div>\n<div id=\"Image1\" class=\"widget Image\" style=\"text-align: center;\"><\/div>\n<div id=\"Image1\" class=\"widget Image\" style=\"text-align: center;\"><\/div>\n<div id=\"Image1\" class=\"widget Image\" style=\"text-align: center;\"><\/div>\n<p><strong>Os recuerdo que pod\u00e9is seguir a Meteosojuela en<\/strong><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/Meteosojuela\/\" rel=\"external nofollow\"><span style=\"color: #0000ff;\"><strong>FACEBOOK<\/strong><\/span><\/a><\/p>\n<p><a href=\"https:\/\/twitter.com\/meteosojuela\" rel=\"external nofollow\"><span style=\"color: #0000ff;\"><strong>TWITER<\/strong><\/span><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.instagram.com\/meteosojuela.larioja\/\" rel=\"external nofollow\"><strong>INSTAGRAM<\/strong><\/a><\/span><\/p>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Y la verdad es que desde el punto de vista meteorol\u00f3gico no pueden tener mejor aspaecto. No quitabamos el ojo durante la semana a la DANA (Gota Fr\u00eda) situada en el sur peninsular donde esta dejando fuertes tormentas e inundaciones y que esperabamos que se acercase hacia nuestra regi\u00f3n como al final no ocurri\u00f3. As\u00ed [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":2743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,12],"tags":[109,697,257,534,618],"class_list":["post-2740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-previsiones-2","category-situaciones-y-acontecimientos","tag-calor","tag-etsable","tag-fiestas","tag-san-mateo","tag-veraniego"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/comments?post=2740"}],"version-history":[{"count":1,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2740\/revisions"}],"predecessor-version":[{"id":2746,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/2740\/revisions\/2746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media\/2743"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media?parent=2740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/categories?post=2740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/tags?post=2740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}