{"id":301,"date":"2014-03-29T15:50:08","date_gmt":"2014-03-29T14:50:08","guid":{"rendered":"http:\/\/blogs.larioja.com\/eltiempo\/?p=301"},"modified":"2014-03-29T15:50:08","modified_gmt":"2014-03-29T14:50:08","slug":"ha-llovido-barro","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/eltiempo\/2014\/03\/29\/ha-llovido-barro\/","title":{"rendered":"\u00a1 Ha llovido barro&#8230;..! Polvo en suspensi\u00f3n"},"content":{"rendered":"<div style=\"text-align: left;\" dir=\"ltr\">\n<p><span style=\"font-size: large;\">Me comentab\u00e1is hace unas horas que\u00a0 hab\u00eda llovido barro&#8230;.que estaba todo hecho un asco&#8230;&#8230;que como era esto posible..<\/span><span style=\"font-size: large;\">Pues efectivamente, as\u00ed ha sucedido&#8230;&#8230;<\/span><\/p>\n<p><span style=\"font-size: large;\">Como bien comentabamos en los pron\u00f3sticos, llevamos unos d\u00edas con una potente borrasca situada en el Sw pen\u00ednsular que esta generando vientos intensos del S-Sw-Se&#8230;<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-CaSlW3S_UEE\/UzSdMCQ41II\/AAAAAAAARfk\/flXfs4F311g\/s1600\/borrasca2703.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/2.bp.blogspot.com\/-CaSlW3S_UEE\/UzSdMCQ41II\/AAAAAAAARfk\/flXfs4F311g\/s1600\/borrasca2703.jpg\" alt=\"\" width=\"640\" height=\"448\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\">\u00a0As\u00ed la pod\u00edamos ver en la im\u00e1gen de vientos de superficie de la NASA&#8230;.<\/span><\/p>\n<div style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"\/\/www.youtube.com\/embed\/P6j56QREBMA?rel=0&#038;autoplay=1\" frameborder=\"0\" width=\"640\" height=\"480\"><\/iframe><\/div>\n<p><span style=\"font-size: large;\"><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: large;\">Y as\u00ed iba a evolucionar durante los pr\u00f3ximos d\u00edas&#8230;..<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-kS8cJXSRK0U\/UzSgPVTqTXI\/AAAAAAAARfw\/1h-ycsm11_k\/s1600\/borrasca2703+1.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-kS8cJXSRK0U\/UzSgPVTqTXI\/AAAAAAAARfw\/1h-ycsm11_k\/s1600\/borrasca2703+1.jpg\" alt=\"\" width=\"400\" height=\"291\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\">Y\u00a0 lo que sucede es que estos vientos arrastran polvo en suspensi\u00f3n, peque\u00f1as part\u00edculas de arena,\u00a0 procedente de las zonas des\u00e9rticas de Africa.<\/span><\/p>\n<p><span style=\"font-size: large;\">Recordad que en los sistemas de bajas presiones los vientos giran en sentido antihorario y el aire c\u00e1lido asciende hacia capas altas de la atm\u00f3sfera&#8230;.(al rev\u00e9s que en el anticicl\u00f3n)&#8230;<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/-DFF28TwxfyM\/Uzb1gooFs9I\/AAAAAAAARhg\/lX7I1Y7ygGc\/s1600\/borrascayanti.png\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/3.bp.blogspot.com\/-DFF28TwxfyM\/Uzb1gooFs9I\/AAAAAAAARhg\/lX7I1Y7ygGc\/s1600\/borrascayanti.png\" alt=\"\" width=\"400\" height=\"212\" border=\"0\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-jOdrlz2-UkM\/Uzb1gp4bfAI\/AAAAAAAARhc\/kcdvUEq-5WQ\/s1600\/borrasca+yanti.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-jOdrlz2-UkM\/Uzb1gp4bfAI\/AAAAAAAARhc\/kcdvUEq-5WQ\/s1600\/borrasca+yanti.jpg\" alt=\"\" width=\"400\" height=\"88\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: large;\">Las bajas presiones del Norte de Africa hacen un &#8220;efecto de succi\u00f3n&#8221; de este polvo en suspensi\u00f3n y una vez en capas altas es transportado por esas potentes corrientes de viento sur hacia latitudes m\u00e1s altas <\/span><\/p>\n<p><span style=\"font-size: large;\">Luego se junta con las gotitas que forman las nubes y cuando precipita lo hace en forma de barro.<\/span><\/p>\n<p><span style=\"font-size: large;\">Fijaos en los mapas del polvo en suspensi\u00f3n de hoy&#8230;<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-UhbpVHiW7P0\/UzbbecAKxOI\/AAAAAAAARhM\/9Dm7IaK9KZc\/s1600\/polvoen+suspension.png\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/4.bp.blogspot.com\/-UhbpVHiW7P0\/UzbbecAKxOI\/AAAAAAAARhM\/9Dm7IaK9KZc\/s1600\/polvoen+suspension.png\" alt=\"\" width=\"640\" height=\"630\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\">\u00a0El polvo procedente de Africa llega hasta zonas del Norte pen\u00ednsular abarcando zonas de nuestra regi\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: large;\">Si ten\u00e9is ocasi\u00f3n de subir a la sierra podr\u00e9is observar como la nieve tambi\u00e9n tiene un zonas te\u00f1idas de marr\u00f3n&#8230;.y es tambi\u00e9n este polvo en suspensi\u00f3n. <\/span><\/p>\n<p><span style=\"font-size: large;\">Y esa es la explicaci\u00f3n. <\/span><\/p>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me comentab\u00e1is hace unas horas que\u00a0 hab\u00eda llovido barro&#8230;.que estaba todo hecho un asco&#8230;&#8230;que como era esto posible..Pues efectivamente, as\u00ed ha sucedido&#8230;&#8230; Como bien comentabamos en los pron\u00f3sticos, llevamos unos d\u00edas con una potente borrasca situada en el Sw pen\u00ednsular que esta generando vientos intensos del S-Sw-Se&#8230; \u00a0As\u00ed la pod\u00edamos ver en la im\u00e1gen de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,12],"tags":[87,475],"class_list":["post-301","post","type-post","status-publish","format-standard","hentry","category-terminos-y-conceptos","category-situaciones-y-acontecimientos","tag-barro","tag-polvo-en-suspension"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}