{"id":855,"date":"2015-10-11T08:30:22","date_gmt":"2015-10-11T06:30:22","guid":{"rendered":"http:\/\/blogs.larioja.com\/eltiempo\/?p=855"},"modified":"2015-10-11T08:30:22","modified_gmt":"2015-10-11T06:30:22","slug":"ciclon-huracan-borrasca-ciclogenesis","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/eltiempo\/2015\/10\/11\/ciclon-huracan-borrasca-ciclogenesis\/","title":{"rendered":"Cicl\u00f3n, hurac\u00e1n, tif\u00f3n, ciclog\u00e9nesis&#8230;\u00bfsabes en qu\u00e9 se diferencian?&#8230;"},"content":{"rendered":"<div style=\"text-align: left;\" dir=\"ltr\">\n<p style=\"text-align: center;\"><span style=\"font-size: large;\"><span style=\"color: #0000ff;\">ACLARANDO TERMINOS&#8230;..<\/span><\/span><\/p>\n<p><span style=\"font-size: large;\">Ultimamente es frecuente escuchar en los medios que huracanes, ciclog\u00e9nesis u otros fen\u00f3menos se dirigen hacia la pen\u00ednsula alarmando a la poblaci\u00f3n&#8230;&#8230;&#8230;sin embargo conviene decir que algunos de estos procesos nunca podr\u00e1n llegar hasta nuestro pa\u00eds.<\/span><\/p>\n<p><span style=\"font-size: large;\">Es por eso que me he decidido a escribir este post para intentar aclarar conceptos.<br \/>\n<\/span><\/p>\n<p><span style=\"font-size: large;\">Y es que llevamos unos d\u00edas hablando\u00a0 que durante pr\u00f3ximas jornadas ibamos a sufrir los efectos del <strong>hurac\u00e1n Joaqu\u00edn<\/strong>, sin embargo esto no es as\u00ed, ya que lo correcto es decir que nos afectan frentes asociados a una borrasca originada por los restos de dicho hurac\u00e1n.<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-6NViEWsf4L4\/Vhg8OrRrPjI\/AAAAAAAAnrw\/bXRleONKG9g\/s1600\/MOV8-4.11L.GIF\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-6NViEWsf4L4\/Vhg8OrRrPjI\/AAAAAAAAnrw\/bXRleONKG9g\/s640\/MOV8-4.11L.GIF\" alt=\"\" width=\"640\" height=\"480\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\"><br \/>\n<\/span><br \/>\n<span style=\"font-size: large;\">Y es que hay que diferenciar desde el punto de vista meteorol\u00f3gico entre unos t\u00e9rminos y otros, porque un <strong>hurac\u00e1n<\/strong> no es lo mismo que una<strong> tormenta tropical<\/strong> o que una <strong>borrasca extratropical<\/strong>, aunque s\u00ed es lo mismo que un<strong> tif\u00f3n<\/strong>.<\/span><\/p>\n<p><span style=\"font-size: large;\">Vamos a ver cuales son estas diferencias&#8230;<\/span><\/p>\n<p><span style=\"font-size: large;\"><strong>Cicl\u00f3n<\/strong> , <strong>hurac\u00e1n<\/strong> y <strong>tif\u00f3n<\/strong> son el mismo fen\u00f3meno, pero su denominaci\u00f3n varia en funci\u00f3n del lugar donde se produce.<\/span><br \/>\n<span style=\"font-size: large;\">Un<span style=\"color: blue;\"> <strong>Cicl\u00f3n Tropical<\/strong><\/span> es un sistema de tormenta <strong>no frontal <\/strong>caracterizado por un centro de baja presi\u00f3n, bandas de lluvias en espiral y fuertes<br \/>\nvientos. Normalmente se origina sobre <strong>aguas tropicales o subtropicales<\/strong>, y rota en el sentido de las agujas del reloj en el hemisferio sur y en<br \/>\ndirecci\u00f3n opuesta en el hemisferio norte.<\/span><\/p>\n<p><span style=\"font-size: large;\">L<\/span><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\">a forma en que obtienen su energ\u00eda es la <strong>liberaci\u00f3n de calor latente y la convecci\u00f3n, <\/strong>debido a la fuerte radici\u00f3n solar existente en estas zonas. <\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\">Este cicl\u00f3n se denomina<span style=\"color: blue;\"> <strong>Hurac\u00e1n<\/strong><\/span> cuando <\/span><span style=\"font-size: large;\">esto sucede en el Oc\u00e9ano Atl\u00e1ntico Norte, el Mar de Caribe, el norte del Pac\u00edfico este y el golfo de M\u00e9xico. y los vientos superan los 120 km\/h<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-e9d6XYkOASo\/Vhg_YwuJx1I\/AAAAAAAAnr8\/9GEygqTotXo\/s1600\/vis-animated.gif\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-e9d6XYkOASo\/Vhg_YwuJx1I\/AAAAAAAAnr8\/9GEygqTotXo\/s640\/vis-animated.gif\" alt=\"\" width=\"640\" height=\"426\" border=\"0\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><\/div>\n<p><span style=\"font-size: large;\">\u00a0(Im\u00e1genes del hurac\u00e1n Joaqu\u00edn)<\/span><\/p>\n<p><span style=\"font-size: large;\"><br \/>\n<\/span><br \/>\n<span style=\"font-size: large;\">Se denomima <strong><span style=\"color: blue;\">Tif\u00f3n<\/span> <\/strong>cuando el cicl\u00f3n se localiza en el <\/span><span style=\"font-size: large;\">Pac\u00edfico oeste y en el oc\u00e9ano \u00cdndico. <\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><span style=\"font-size: large;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-eof0P5eXgRQ\/UjzCR4N6XfI\/AAAAAAAAMSA\/QMplQalXFJs\/s1600\/usagi.gif\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-eof0P5eXgRQ\/UjzCR4N6XfI\/AAAAAAAAMSA\/QMplQalXFJs\/s640\/usagi.gif\" alt=\"\" width=\"640\" height=\"425\" border=\"0\" \/><\/a><\/span><\/div>\n<p><span style=\"font-size: large;\">\u00a0(Im\u00e1genes del Tif\u00f3n Usagi sobre Filipinas, hace unos a\u00f1os)<\/span><\/p>\n<div class=\"VerdMoyenDen\"><span style=\"font-size: large;\">Los <strong>nombres de los huracanes y tifones<\/strong> siempre son de hombre o de mujer. Cada a\u00f1o, se prepara una lista posible de nombres para la\u00a0 temporada de huracanes. La lista contiene un nombre por cada letra del alfabeto (las letras Q, U, X, Y, Z no se incluyen debido a que pocos nombres empiezan con esas letras).\u00a0<\/span><br \/>\n<span style=\"font-size: large;\">Estas listas son recicladas cada seis a\u00f1os y se reemplazan los nombres cuando el nombre de un hurac\u00e1n ha sido retirado.<\/span><\/div>\n<div class=\"VerdMoyenDen\">\n<p><span style=\"font-size: large;\">Los nombres de huracanes muy destructivos se retiran, quedando en los registros hist\u00f3ricos, y son sustituidos por otros que inician con la misma letra.<\/span><\/p>\n<p><span style=\"font-size: large;\">Por otra parte, es muy importante tambi\u00e9n definir que diferencias existen entre un <strong>hurac\u00e1n<\/strong>, una <strong>tormenta tropical<\/strong> y una<strong> borrasca extratropical<\/strong> ya que estos sistemas, en su evoluci\u00f3n, son los que nos afectan a nosotros y muchas veces causan confusi\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: large;\">Como ya hemos dicho un <strong><span style=\"color: blue;\">Hurac\u00e1n<\/span><\/strong> es un sistema de baja presi\u00f3n originado en zonas tropicales o subtropicales, alimentado por el calor y la humedad de las aguas de esos mares que provocan intensos procesos convectivos. Los vientos superan los 120 km\/h.<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-yc5D8YBTv2k\/Vhi3UuEibhI\/AAAAAAAAns8\/8P94qiv9cV8\/s1600\/144210W5_NL_sm.gif\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/4.bp.blogspot.com\/-yc5D8YBTv2k\/Vhi3UuEibhI\/AAAAAAAAns8\/8P94qiv9cV8\/s640\/144210W5_NL_sm.gif\" alt=\"\" width=\"640\" height=\"512\" border=\"0\" \/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><\/div>\n<p><span style=\"font-size: large;\">En su evoluci\u00f3n estos sistemas tienden a ascender de latitud, entrando en contacto con aguas m\u00e1s fr\u00edas, lo que da lugar a una menor disposici\u00f3n de &#8220;combustible&#8221; y por lo tanto una disminuci\u00f3n de los fen\u00f3menos convectivos y en consecuencia de la virulencia del fen\u00f3meno.<\/span><\/p>\n<p><span style=\"font-size: large;\">Se produce\u00a0 un ascenso de presi\u00f3n y una disminuci\u00f3n de la intensidad de los vientos (menos de 120 km\/h) hablar\u00edamos entonces de <span style=\"color: blue;\"><strong>Tormenta tropical.<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\">Cuando esta tormenta entra dentro de la circulaci\u00f3n atmosf\u00e9rica general,\u00a0 dominada por el chorro polar en altura y por lo vientos del oeste en superfice en nuestras latitudes medias, comienza a alimentarse de aire fr\u00edo&#8230;<\/span><\/p>\n<\/div>\n<div class=\"VerdMoyenDen\">\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"https:\/\/1.bp.blogspot.com\/-FAoPng3DJYY\/VgE18_-gWzI\/AAAAAAAAmyA\/qwGnjDguLu0\/s1600\/La-corriente-en-chorro_54414658491_53699622600_601_341.jpg\" rel=\"external nofollow\"><img decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-FAoPng3DJYY\/VgE18_-gWzI\/AAAAAAAAmyA\/qwGnjDguLu0\/s640\/La-corriente-en-chorro_54414658491_53699622600_601_341.jpg\" alt=\"http:\/\/1.bp.blogspot.com\/-FAoPng3DJYY\/VgE18_-gWzI\/AAAAAAAAmyA\/qwGnjDguLu0\/s640\/La-corriente-en-chorro_54414658491_53699622600_601_341.jpg\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\">..se considera entonces que el fen\u00f3meno se ha extratropicalizado y, en dependencia del contraste de temperaturas entre la masa de aire fr\u00edo polar y la c\u00e1lida tropical, se origina una borrasca m\u00e1s o menos profunda, es entonces cuando consideramos que aparece una <span style=\"color: blue;\"><strong>Borrasca Extratropical<\/strong><\/span> con sus frentes ya organizados&#8230;&#8230;y esos frentes son los que nos suelen afectar&#8230;<\/span><\/span><\/span><\/span><\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-hF_O13nlGOI\/VhhOsSkjwhI\/AAAAAAAAnsQ\/atlDOv1lGVI\/s1600\/exjoaquin.gif\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/2.bp.blogspot.com\/-hF_O13nlGOI\/VhhOsSkjwhI\/AAAAAAAAnsQ\/atlDOv1lGVI\/s640\/exjoaquin.gif\" alt=\"\" width=\"640\" height=\"432\" border=\"0\" \/><\/a><\/div>\n<div style=\"text-align: center;\"><\/div>\n<p><span style=\"font-size: large;\">Si cogemos la animaci\u00f3n de la evoluci\u00f3n del hurac\u00e1n Joaqu\u00edn en los d\u00edas pasados esta ser\u00eda m\u00e1s o menos, la secuencia correcta del proceso.<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/4.bp.blogspot.com\/-8ZQHkdsk0iE\/VhhXgZEBTOI\/AAAAAAAAnsg\/xfHDIIRq9co\/s1600\/POSTHURACAN.gif\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/4.bp.blogspot.com\/-8ZQHkdsk0iE\/VhhXgZEBTOI\/AAAAAAAAnsg\/xfHDIIRq9co\/s640\/POSTHURACAN.gif\" alt=\"\" width=\"640\" height=\"474\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\">Cuando estas borrascas extratropicales, en su formaci\u00f3n, se profundiz\u00e1n de forma muy r\u00e1pida&#8230;.entre 20-24hPa en 24 horas hablamos de<span style=\"color: blue;\"> <strong>Ciclog\u00e9nesis Explosiva.<\/strong><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\"><span style=\"color: blue;\"><span style=\"color: black;\">Remarco aqu\u00ed el hecho de que una ciclog\u00e9nesis explosiva, nunca nos podr\u00e1 afectar, (como muchas veces vemos en los medios)<\/span><\/span><\/span><\/span><\/span><\/span><\/span><span style=\"font-size: large;\"> porque<strong> NO <\/strong>es una entidad, <strong>ES UN PROCESO<\/strong>.\u00a0<\/span><span style=\"font-size: large;\">Los t\u00e9rminos correctos son:&#8221; Frentes asociados a una profunda borrasca atl\u00e1ntica, que su formaci\u00f3n (<strong>CICLO-GENESIS<\/strong>) se produce de una forma r\u00e1pida y profunda (<strong>EXPLOSIVA<\/strong>= ca\u00edda de 20-24hPa en 24 horas), afectar\u00e1n a la pen\u00ednsula&#8221;.\u00a0<\/span><\/p>\n<\/div>\n<div class=\"VerdMoyenDen\" style=\"text-align: center;\"><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\"><span style=\"color: blue;\"><span style=\"color: black;\">\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/2.bp.blogspot.com\/-WwVUdQJDNCE\/VDziHd91ONI\/AAAAAAAAXVQ\/0qJKA5gPdbE\/s1600\/CICLOGENESIS3.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/2.bp.blogspot.com\/-WwVUdQJDNCE\/VDziHd91ONI\/AAAAAAAAXVQ\/0qJKA5gPdbE\/s1600\/CICLOGENESIS3.jpg\" alt=\"\" width=\"640\" height=\"442\" border=\"0\" \/><\/a><\/div>\n<div class=\"VerdMoyenDen\">\n<p><span style=\"font-size: large;\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1\"><span data-ft=\"{\"tn\":\"K\"}\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body\"><span class=\"UFICommentBody\" data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0\"><span data-reactid=\".is.1:5.0.1:$comment327908497395427_327920837394193\/=10.0.$right.0.$left.0.0.1.$comment-body.0.$end\/=1$text0\/=010\"><span style=\"color: blue;\"><span style=\"color: black;\">\u00a0<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<div style=\"text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-TU-6QmRE09k\/VD0skp82tKI\/AAAAAAAAXWU\/dpaJTkLIt8Q\/s1600\/ciclogenesis.png\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-TU-6QmRE09k\/VD0skp82tKI\/AAAAAAAAXWU\/dpaJTkLIt8Q\/s1600\/ciclogenesis.png\" alt=\"\" width=\"640\" height=\"436\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\">Y ya por \u00faltimo vamos a hacer un peque\u00f1o inciso en otros t\u00e9rminos que tambi\u00e9n generan algo de confusi\u00f3n como son los &#8230;.Tornados , trombas y mangas.<\/span><\/p>\n<\/div>\n<div class=\"VerdMoyenDen\"><span style=\"font-size: large;\">Un <span style=\"color: blue;\"><strong>Tornado<\/strong><\/span> es un <\/span><span style=\"font-size: large;\">torbellino violento que se extiende desde las nubes (cumulonimbos) hasta la superficie terrestre.\u00a0<\/span><\/div>\n<p><span style=\"font-size: large;\">Para que se origine un tornado es necesaria la confluencia de una masa de aire c\u00e1lido y h\u00famedo, otra masa de aire fr\u00edo y seco, y una corriente ascendente.<\/span><\/p>\n<p><span style=\"font-size: large;\"> El di\u00e1metro de un tornado es m\u00e1s peque\u00f1o que el de un cicl\u00f3n tropical Los tornados se desplazan r\u00e1pidamente ysus vientos pueden alcanzar velocidades de 400 kil\u00f3metros por hora (250millas por hora) o m\u00e1s, cambian de direcci\u00f3n de forma err\u00e1tica y causan gran destrucci\u00f3n.<\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-unk_smZ7JS4\/UjzGZyQccPI\/AAAAAAAAMSQ\/13z4zxeXu4Q\/s1600\/tornado.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-unk_smZ7JS4\/UjzGZyQccPI\/AAAAAAAAMSQ\/13z4zxeXu4Q\/s640\/tornado.jpg\" alt=\"\" width=\"640\" height=\"360\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/-WfijVmkzpnY\/UjzGaGliQZI\/AAAAAAAAMSU\/7k6ybn6yFYI\/s1600\/TornadoBig.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/3.bp.blogspot.com\/-WfijVmkzpnY\/UjzGaGliQZI\/AAAAAAAAMSU\/7k6ybn6yFYI\/s640\/TornadoBig.jpg\" alt=\"\" width=\"640\" height=\"480\" border=\"0\" \/><\/a><\/div>\n<div class=\"VerdMoyenDen\"><span style=\"font-size: large;\">\u00a0(Son t\u00edpicos de las grandes llanuras de Norte\u00e1merica)<\/span><\/div>\n<div class=\"VerdMoyenDen\"><\/div>\n<div class=\"VerdMoyenDen\">\n<p><span style=\"font-size: large;\">Si este fen\u00f3meno ocurre sobre el \u00f3ceano o lagos de denomina <span style=\"color: blue;\"><strong>Tromba o Manga Marina<\/strong><\/span><\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/1.bp.blogspot.com\/-FpTXzdBWJYg\/UjzH2OCd8LI\/AAAAAAAAMSk\/pGdZqQOgLc4\/s1600\/Tromba_marina_Estrecho_de_Gibraltar.jpg\" rel=\"external nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"\/\/1.bp.blogspot.com\/-FpTXzdBWJYg\/UjzH2OCd8LI\/AAAAAAAAMSk\/pGdZqQOgLc4\/s640\/Tromba_marina_Estrecho_de_Gibraltar.jpg\" alt=\"\" width=\"640\" height=\"424\" border=\"0\" \/><\/a><\/div>\n<p><span style=\"font-size: large;\"><strong>\u00a0<\/strong>(Esta im\u00e1gen es del Estrecho de Gibraltar)\u00a0<\/span><\/p>\n<p><span style=\"font-size: large;\">Estaremos atentos a la llegada de esa borrasca extratropical a Espa\u00f1a..<\/span><br \/>\n<span style=\"font-size: large;\">Os recuerdo que pod\u00e9is seguir a Meteosojuela en:<\/span><\/p>\n<p><span style=\"font-size: large;\"><a href=\"https:\/\/www.facebook.com\/Meteosojuela\" rel=\"external nofollow\">FACEBOOK <\/a><\/span><\/p>\n<p><a href=\"https:\/\/twitter.com\/meteosojuela\" rel=\"external nofollow\"><span style=\"font-size: large;\">TWITER<\/span><\/a><\/p>\n<p><a href=\"https:\/\/instagram.com\/meteosojuela\/\" rel=\"external nofollow\"><span style=\"font-size: large;\">INSTAGRAM<\/span><\/a><\/p>\n<p><span style=\"font-size: large;\">Si te gusta compartelo \ud83d\ude42<\/span><\/p>\n<p>Fuentes: NOAA,RAM meteorologia, Mario Fern\u00e1ndez, Internet, propias)<\/p>\n<\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>ACLARANDO TERMINOS&#8230;.. Ultimamente es frecuente escuchar en los medios que huracanes, ciclog\u00e9nesis u otros fen\u00f3menos se dirigen hacia la pen\u00ednsula alarmando a la poblaci\u00f3n&#8230;&#8230;&#8230;sin embargo conviene decir que algunos de estos procesos nunca podr\u00e1n llegar hasta nuestro pa\u00eds. Es por eso que me he decidido a escribir este post para intentar aclarar conceptos. Y es [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[96,141,143,151,304,367,582,587,591],"class_list":["post-855","post","type-post","status-publish","format-standard","hentry","category-terminos-y-conceptos","tag-borrasca","tag-ciclogenesis","tag-ciclogenesis-explosiva","tag-ciclon","tag-huracan","tag-manga","tag-tifon","tag-tormenta","tag-tormenta-extratropical"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/comments?post=855"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/posts\/855\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/media?parent=855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/categories?post=855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/eltiempo\/wp-json\/wp\/v2\/tags?post=855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}