{"id":86,"date":"2007-09-12T11:08:28","date_gmt":"2007-09-12T11:08:28","guid":{"rendered":"http:\/\/blogs.larioja.com\/entrenosotros\/?p=86"},"modified":"2007-09-12T11:08:28","modified_gmt":"2007-09-12T11:08:28","slug":"y-mi-me-cuenta","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/entrenosotros\/2007\/09\/12\/y-mi-me-cuenta\/","title":{"rendered":"\u00a1Y a m\u00ed qu\u00e9 me cuenta!"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><span style=\"color: windowtext;\">Fuimos a despedir a nuestro hijo mayor al aeropuerto, camino de uno de esos presuntos cursos de verano para practicar ingl\u00e9s.Ten\u00edamos que estar de vuelta en Logro\u00f1o para recoger a su hermana, el avi\u00f3n no despegaba, no daban informaci\u00f3n de la hora prevista y, como empezaba a correr el rumor de que el vuelo se anulaba, fuimos al mostrador de la compa\u00f1\u00eda a\u00e9rea a ver si alguien nos aclaraba algo. La contestaci\u00f3n fue inolvidable: \u201c\u00a1Y a m\u00ed qu\u00e9 me cuenta! Yo s\u00f3lo trabajo aqu\u00ed\u201d. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><span style=\"color: windowtext;\">Al salir de vacaciones te las prometes tan felices, pero \u00a1ay si te pierden la maleta con todos los objetos personales! o si cancelan en el \u00faltimo momento el vuelo que te iba a llevar a ese lugar paradis\u00edaco o esa habitaci\u00f3n en primera l\u00ednea de playa, en la que tanto has insistido, resulta que es con vistas a un muro de hormig\u00f3n, est\u00e1 en el primero y tiene debajo los enormes extractores de la cocina del hotel. O ese aire acondicionado que no funciona \u2013para una semana que has podido pagarte de vacaciones- y no hay otra habitaci\u00f3n a la que cambiarte, \u201cqu\u00e9 le vamos a hacer, es la \u00fanica disponible, \u00a1a m\u00ed qu\u00e9 me cuenta!\u201d.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><span style=\"color: windowtext;\">Ya puedes ponerte a llamar, que dar\u00e1 igual. Para empezar, el n\u00famero telef\u00f3nico de contacto de equipajes extraviados es el m\u00e1s dif\u00edcil de conseguir, y suele ofrecer la se\u00f1al de ocupado o, sencillamente, nadie contesta al otro lado de la l\u00ednea cuando, con suerte, se logra que entre la llamada. Pero si tienes la fortuna de que te contesten al tel\u00e9fono, te van pasando con distintas personas a las que tienes que explicar todo desde el principio. Toman nota, ya te avisar\u00e1n, nadie asume la responsabilidad, nadie da la cara, echan balones fuera y si insistes te dir\u00e1n: \u201c\u00a1Y a m\u00ed qu\u00e9 me cuenta! Yo s\u00f3lo tomo nota\u201d. <o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><span style=\"color: windowtext;\">Los que m\u00e1s cabrean son los \u201ca m\u00ed qu\u00e9 me cuenta\u201d de la pol\u00edtica, como hemos visto en Catalu\u00f1a este verano, con los apagones, el calvario de los trenes de cercan\u00edas o los permanentes atascos en los peajes de la autopista&#8230; En Logro\u00f1o, sin ir m\u00e1s lejos, hemos tenido un episodio de \u201ca m\u00ed qu\u00e9 cuenta\u201d con las im\u00e1genes tercermundistas de las colas interminables despu\u00e9s de madrugones inveros\u00edmiles para renovar el DNI.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><span style=\"color: windowtext;\"><span style=\"\"> <\/span>Est\u00e1 claro que los jefes y los pol\u00edticos tienen responsabilidades, pero no son los \u00fanicos. La eficacia de una organizaci\u00f3n o de una empresa reside en que cada uno se implique, asuma su responsabilidad y no escurra el bulto. Una de las claves es ponerse en el lugar del otro. Pero siempre pensamos que son los dem\u00e1s los que tienen que ponerse en nuestro lugar. \u00bfY al rev\u00e9s? \u00bfQui\u00e9n no se ha sacudido un problema alguna vez con un \u201cy a m\u00ed qu\u00e9 me cuenta\u201d?<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\">El problema es que una sucesi\u00f3n en cadena de los \u201cy a m\u00ed qu\u00e9 me cuenta\u201d conduce al caos, a una situaci\u00f3n donde curiosamente nadie ha creado los problemas, pero tampoco nadie quiere saber nada de ellos ni pone los medios para solucionarlos. Mientras, los ciudadanos nos quedamos en la m\u00e1s absoluta soledad y desconcierto, completamente indefensos ante la epidemia del \u201cy a m\u00ed qu\u00e9 me cuenta\u201d.<span style=\"color: windowtext;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: 27pt;\"><IMG src=\"\/\/static-blogs.larioja.com\/..\/entrenosotros\/files\/19293_1154250155_extras_albumes_0.jpg\" id=\"img_0\" class=\"imgcen\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Fuimos a despedir a nuestro hijo mayor al aeropuerto, camino de uno de esos presuntos cursos de verano para practicar ingl\u00e9s.Ten\u00edamos que estar de vuelta en Logro\u00f1o para recoger a su hermana, el avi\u00f3n no despegaba, no daban informaci\u00f3n de la hora prevista y, como empezaba a correr el rumor de que el vuelo se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}