{"id":89,"date":"2007-10-24T10:34:42","date_gmt":"2007-10-24T10:34:42","guid":{"rendered":"http:\/\/blogs.larioja.com\/entrenosotros\/?p=89"},"modified":"2007-10-24T10:34:42","modified_gmt":"2007-10-24T10:34:42","slug":"me-da-la-nariz","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/entrenosotros\/2007\/10\/24\/me-da-la-nariz\/","title":{"rendered":"Me da en la nariz"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><br \/>\n<\/span><IMG src=\"\/\/farm1.static.flickr.com\/199\/486462070_81e671e7ec.jpg\" id=\"img_0\"><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\">Autor de la imagen: <A href=\"http:\/\/www.flickr.com\/photos\/haciendoclack\/486462070\/\" title=\"http:\/\/www.flickr.com\/photos\/haciendoclack\/486462070\/\" id=\"link_0\">haciendoclack<\/a> <\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\">Reproducida con permiso del autor<\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\">Todos los derechos reservados por el autor  de la imagen <\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\">\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">Lanzan olores a la calle. En los centros comerciales, en los restaurantes, en las tiendas, en los hoteles, la \u00faltima t\u00e9cnica para atraer a m\u00e1s clientes es lanzar olores agradables. Olores que nos relajan, que nos tranquilizan, que nos transportan a la infancia o que nos incitan a comprar. No ha llegado todav\u00eda a Logro\u00f1o, supongo que ser\u00e1 cuesti\u00f3n de tiempo. Los olores est\u00e1n de moda para vender m\u00e1s.<span> <\/span><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">En Jap\u00f3n han puesto en marcha unos cines en los que sincronizan los olores con la pel\u00edcula, de forma que, mientras est\u00e1s c\u00f3modamente instalado en la butaca, puedes sentir el aroma de las escenas de la pel\u00edcula. Lo probaron con \u201cCharlie y la f\u00e1brica de chocolate\u201d y los espectadores salieron encantados. En otras pel\u00edculas lanzaban fragancias florales en las escenas rom\u00e1nticas y olor a hierbabuena y romero en los momentos m\u00e1s tristes. Aplicado esto a los documentales de naturaleza, tendr\u00eda un efecto m\u00e1s que relajante. Otro efecto muy distinto tendr\u00eda el hacerlo en las escenas de sexo.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">En las pel\u00edculas que giran en torno a la comida ser\u00eda una maravilla. Sin ir m\u00e1s lejos, dos recientes: este verano vimos con la peque\u00f1a una pel\u00edcula que es una apolog\u00eda de los aromas en la cocina, \u201cRatatouille\u201d, que con olores incorporados ser\u00eda el no va m\u00e1s; o podemos imaginarnos la reci\u00e9n estrenada en Espa\u00f1a \u201cSin reservas\u201d, que transcurre en su mayor parte en la cocina de un restaurante.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">Un amigo que ten\u00eda que cambiarse de ciudad, me contaba que para vender m\u00e1s f\u00e1cilmente su piso, cuando ten\u00eda que ense\u00f1arlo a un posible comprador cocinaba un bizcocho porque ese aroma le daba un toque m\u00e1s hogare\u00f1o a la vivienda y as\u00ed podr\u00eda venderlo antes. En efecto, no tard\u00f3 mucho en conseguirlo. Ten\u00eda buen olfato.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><o:p><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">Cuando estamos estresados o deprimidos, una de las cosas que m\u00e1s nos reconforta, que m\u00e1s nos devuelve el equilibrio o la armon\u00eda, es el olor de las personas que queremos. El olor de tu pareja, de tus hijos, de tu casa, ese olor caracter\u00edstico que tenemos en alg\u00fan lugar del cerebro, nos devuelve el sentido de la vida y pone las cosas en su sitio. Una buena terapia en momentos de estr\u00e9s es recordar olores agradables, \u00a1si pudi\u00e9ramos tener amano el olor de un horno de pan, de un beb\u00e9, del mar&#8230;! Por el contrario, hay olores que nos estresan, que te sacan de quicio, que te desagradan; cuando barruntamos un problema o cuando algo no nos gusta, decimos \u201cesto no me huele bien\u201d.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\"><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-indent: 27pt; text-align: justify;\"><span style=\"font-family: Arial;\">La publicidad est\u00e1 pensada para que nos entre por la vista, pero se ha comprobado que una gran parte de nuestras sensaciones est\u00e1n relacionadas con el olfato. En la Rioja, una tierra de vinos por excelencia, esto lo sabemos bien, porque antes de disfrutar de un Rioja en el paladar, catamos su aroma, su esencia con la nariz (a los sumilleres de les llama &#8220;narices&#8221;). A la vista de las nuevas modas, est\u00e1 claro que el futuro viene cargado de olores, me da en la nariz.<o:p><\/o:p><\/span><\/p>\n<p class=\"MsoBodyTextIndent\">\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Autor de la imagen: haciendoclack Reproducida con permiso del autor Todos los derechos reservados por el autor de la imagen Lanzan olores a la calle. En los centros comerciales, en los restaurantes, en las tiendas, en los hoteles, la \u00faltima t\u00e9cnica para atraer a m\u00e1s clientes es lanzar olores agradables. Olores que nos relajan, que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/entrenosotros\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}