{"id":653,"date":"2013-04-04T08:00:43","date_gmt":"2013-04-04T07:00:43","guid":{"rendered":"http:\/\/blogs.larioja.com\/historias\/?p=653"},"modified":"2013-04-04T08:00:43","modified_gmt":"2013-04-04T07:00:43","slug":"haro-la-rioja-tierra-abierta-dulce-el-general-que-no-hacia-honor-a-su-apellido","status":"publish","type":"post","link":"https:\/\/blogs.larioja.com\/historias\/2013\/04\/04\/haro-la-rioja-tierra-abierta-dulce-el-general-que-no-hacia-honor-a-su-apellido\/","title":{"rendered":"Haro: La Rioja Tierra Abierta. Dulce, el general que no hac\u00eda honor a su apellido"},"content":{"rendered":"<p><a href=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Domingo-dulce-y-sus-alabarderos.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-654\" title=\"Palacio Real 2\" src=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Domingo-dulce-y-sus-alabarderos.jpg\" alt=\"\" width=\"620\" height=\"422\" srcset=\"https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/Domingo-dulce-y-sus-alabarderos.jpg 567w, https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/Domingo-dulce-y-sus-alabarderos-300x205.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Pese a haber protagonizado importantes p\u00e1ginas de la historia de Espa\u00f1a del siglo XIX, no es Domingo Dulce y Garay un personaje especialmente conocido entre sus paisanos. La exposici\u00f3n La Rioja Tierra Abierta, \u2018Las Luces de la Modernidad\u2019, que se celebra en Haro, ha querido recordar a este militar y pol\u00edtico, del que pueden contemplarse en el palacio de Benda\u00f1a su gorro militar, su retrato o su busto.<\/p>\n<p>Dulce naci\u00f3 en la localidad riojana de Sot\u00e9s el 7 de mayo de 1808, cinco d\u00edas despu\u00e9s de que estallara la Guerra de la Independencia. Al igual que muchos j\u00f3venes del siglo XIX, ingres\u00f3 en el Ej\u00e9rcito como cadete a los 15 a\u00f1os, siendo muy pronto ascendido a alf\u00e9rez de Caballer\u00eda. A las \u00f3rdenes del general riojano (de adopci\u00f3n) Baldomero Espartero, combati\u00f3 durante la I Guerra Carlista en el bando liberal. Al concluir la primera guerra civil de la Espa\u00f1a moderna, \u00e9l de Sot\u00e9s ya luc\u00eda en su pecho cuatro cruces Laureadas de San Fernando, fruto de her\u00f3icas acciones militares, as\u00ed como el rango de teniente coronel sobre sus hombreras.<\/p>\n<p>Con el duque de la Victoria en la Regencia de la naci\u00f3n, Domingo Dulce ingreso en la Guardia Real, protagonizando all\u00ed el hecho de armas que lo inmortaliz\u00f3. En 1841, durante una conspiraci\u00f3n militar moderada -otra m\u00e1s de uno u otro signo- los generales Diego de Le\u00f3n y Concha intentaron asaltar el Palacio Real y dar as\u00ed un golpe de mano. La intenci\u00f3n de los rebeldes no era otra que secuestrar a la futura Isabel II y forzar as\u00ed la inestable posici\u00f3n de Espartero. Dulce, que se hallaba de servicio aquella noche, defendi\u00f3 con bravura la escalera que conduc\u00eda a las habitaciones de la reina ni\u00f1a y evit\u00f3 la maniobra al frente de sus alabarderos. Diego de Le\u00f3n fue fusilado y Dulce y sus hombres fueron galardonados por la futura Isabel II. El pundonor del riojano fue recompensado con el estatus de gentilhombre de Su Majestad.<\/p>\n<p><a href=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/El-general-Dulce-en-La-Rioja-Tierra-Abierta.-Justo-Rodr\u00edguez.jpg\"><img loading=\"lazy\" class=\"alignright  wp-image-657\" title=\"El general Dulce en La Rioja Tierra Abierta. Justo Rodr\u00edguez\" src=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/El-general-Dulce-en-La-Rioja-Tierra-Abierta.-Justo-Rodr\u00edguez.jpg\" alt=\"\" width=\"348\" height=\"313\" srcset=\"https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/El-general-Dulce-en-La-Rioja-Tierra-Abierta.-Justo-Rodr\u00edguez.jpg 395w, https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/El-general-Dulce-en-La-Rioja-Tierra-Abierta.-Justo-Rodr\u00edguez-300x270.jpg 300w\" sizes=\"(max-width: 348px) 100vw, 348px\" \/><\/a><\/p>\n<p><strong>General y marqu\u00e9s<\/strong><\/p>\n<p>Ascendido al rango de general, Dulce tom\u00f3 parte en la II Guerra Carlista, durante la que cosech\u00f3 un importante triunfo sobre la huestes de Ram\u00f3n Cabrera, el Tigre del Maestrazgo, en la localidad de Castell-Florite. Fue este top\u00f3nimo oscense el que adornar\u00eda su futuro t\u00edtulo nobiliario: marqu\u00e9s de Castell-Florite. Esta distinci\u00f3n lleg\u00f3 en 1860 cuando, siendo capit\u00e1n general de Catalu\u00f1a, reprimi\u00f3 una asonada carlista en San Carlos de la R\u00e1pita (Tarragona).<\/p>\n<p>El otro hito hist\u00f3rico en el que nombre de Dulce se escribi\u00f3 con letras de oro en el devenir de Espa\u00f1a fue la Revoluci\u00f3n de 1854, popularmente conocida como la Vicalvarada. En julio de ese a\u00f1o, siendo general de Caballer\u00eda, uni\u00f3 sus fuerzas a las de O&#8221;Donnell en el primer golpe serio al reinado de Isabel II. El definitivo llegar\u00eda 14 a\u00f1os despu\u00e9s, con la denominada Revoluci\u00f3n Gloriosa de 1868.<\/p>\n<p><strong>Insurrecci\u00f3n en Cuba<\/strong><\/p>\n<p>Destinado a Cuba como gobernador, desarroll\u00f3 Dulce una meritoria gesti\u00f3n, trufada de generosas disposiciones que le granjearon las simpat\u00edas de los nativos, al tiempo que combat\u00eda a los sublevados de Santo Domingo. Hoy, en los diferentes manuales de la historia de Cuba, Domingo Dulce tiene un papel relevante.<\/p>\n<p>De vuelta a la metr\u00f3poli, fue desterrado a Canarias junto a Serrano por conspiraci\u00f3n. Triunfante la Revoluci\u00f3n del 68, firm\u00f3 el manifiesto \u00abEspa\u00f1a con honra\u00bb.<\/p>\n<p>Pese a estar enfermo, regres\u00f3 Dulce a la Capitan\u00eda General de Cuba, en enero de 1869, pero el \u00e9xito de su primer mandato no le acompa\u00f1\u00f3 esta vez. Como bien explica el aleluya titulada Historia de la Insurrecci\u00f3n y Guerra de Cuba -aqu\u00ed reproducida-, su pol\u00edtica conciliadora tropez\u00f3 con la intransigencia de espa\u00f1olistas y autonomistas. Ambos bandos irreconciliables, como se ver\u00eda finalmente en 1898, llegaron a cercarle en su palacio de La Habana y a forzar su dimisi\u00f3n cinco meses despu\u00e9s de retomar el cargo.<\/p>\n<p>Acudi\u00f3 al balneario franc\u00e9s de Amelie-les-Bains, donde falleci\u00f3 el 23 de noviembre de 1869.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Firma-de-Dulce1.jpg\"><img loading=\"lazy\" class=\" wp-image-656 aligncenter\" title=\"Firma\" src=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Firma-de-Dulce1.jpg\" alt=\"\" width=\"353\" height=\"129\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>DIEZ FECHAS CLAVES<\/strong><\/p>\n<p><strong>1808:<\/strong> Nace en la localidad riojana de Sot\u00e9s, fue cadete de Caballer\u00eda en 1823, y combati\u00f3 en la I Guerra Carlista, contiendo que termin\u00f3 tras el abrazo de Vergara con el empleo de teniente coronel.<\/p>\n<p><strong>1841:<\/strong> Era el jefe del ret\u00e9n de Alabarderos que impidi\u00f3, en el Palacio Real de Madrid, el secuestro de la reina lsabel II por parte de los generales Concha y Diego de Le\u00f3n, este \u00faltimo fusilado d\u00edas despu\u00e9s, durante el frustrado pronunciamiento antiesparterista;<\/p>\n<p><strong>1843:<\/strong> Sufri\u00f3 postergaci\u00f3n por ello al triunfar los moderados tras la ca\u00edda de Espartero y la llegada al poder de Narv\u00e1ez, pero volvi\u00f3 a ocupar destinos importantes desde su ascenso a brigadier en 1847.<\/p>\n<p><strong>1854:<\/strong> Tuvo un papel preponderante tanto en la preparaci\u00f3n como en el desenlace de la revoluci\u00f3n de julio de 1854 -conocida hist\u00f3ricamente como la Vicalvarada- contra el gobierno Sartorius, en el que ocupaba el cargo de director general de Caballer\u00eda).<\/p>\n<p><strong>1860:<\/strong> Cuando ocupaba el empleo de capit\u00e1n general de Catalu\u00f1a, tuvo que actuar y reprimir con contundencia contra la intentona carlista que surgi\u00f3 en la localidad tarraconense de San Carlos de la R\u00e1pita.<\/p>\n<p><strong>1862:<\/strong> Ocupa por primera vez el puesto de capit\u00e1n de general de Cuba hasta 1866.<\/p>\n<p><strong>1868:<\/strong> Tom\u00f3 parte activa en la crisis final del mandato de Isabel II, reina que tuvo que huir a Francia tras la denominada Revoluci\u00f3n Gloriosa. Domingo Dulce era uno de los generales desterrados por el hasta entonces primer ministro Gonz\u00e1lez Bravo. Tambi\u00e9n fue uno de los firmantes del manifiesto Espa\u00f1a con honra.<\/p>\n<p><strong>1869:<\/strong> Pese a estar enfermo, regres\u00f3 a la Capitan\u00eda General de Cuba.<strong><\/strong> Muere en el balneario de Amelie-les-Bains (Francia) el 23 de noviembre.<\/p>\n<p><strong>1962:<\/strong> Se publica la biograf\u00eda Domingo Dulce. General isabelino, a cargo de uno de sus descendientes, marqu\u00e9s de Castell-Florite.<\/p>\n<p><strong>2006:<\/strong> Sot\u00e9s le dedica una plaza a Dulce, marqu\u00e9s de Castell-Florite.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Tumulo-del-general-Dulce-en-Granollers.-La-Ilustraci\u00f3n-Espa\u00f1ola-y-Americana.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-658\" title=\"Tumulo del general Dulce en Granollers. La Ilustraci\u00f3n Espa\u00f1ola y Americana\" src=\"\/historias\/wp-content\/uploads\/sites\/11\/2013\/04\/Tumulo-del-general-Dulce-en-Granollers.-La-Ilustraci\u00f3n-Espa\u00f1ola-y-Americana.jpg\" alt=\"\" width=\"640\" height=\"503\" srcset=\"https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/Tumulo-del-general-Dulce-en-Granollers.-La-Ilustraci\u00f3n-Espa\u00f1ola-y-Americana.jpg 598w, https:\/\/static-blogs.larioja.com\/wp-content\/uploads\/sites\/11\/2013\/04\/Tumulo-del-general-Dulce-en-Granollers.-La-Ilustraci\u00f3n-Espa\u00f1ola-y-Americana-300x236.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pese a haber protagonizado importantes p\u00e1ginas de la historia de Espa\u00f1a del siglo XIX, no es Domingo Dulce y Garay un personaje especialmente conocido entre sus paisanos. La exposici\u00f3n La Rioja Tierra Abierta, \u2018Las Luces de la Modernidad\u2019, que se celebra en Haro, ha querido recordar a este militar y pol\u00edtico, del que pueden [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/posts\/653"}],"collection":[{"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/comments?post=653"}],"version-history":[{"count":0,"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/posts\/653\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/media?parent=653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/categories?post=653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.larioja.com\/historias\/wp-json\/wp\/v2\/tags?post=653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}